{"id":5782,"date":"2024-11-16T14:00:05","date_gmt":"2024-11-16T14:00:05","guid":{"rendered":"https:\/\/www.criptofacil.com\/es\/?p=5782"},"modified":"2024-11-15T17:24:08","modified_gmt":"2024-11-15T17:24:08","slug":"pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin","status":"publish","type":"post","link":"https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/","title":{"rendered":"Pensilvania se adelanta a Trump y propone la creaci\u00f3n de una reserva estrat\u00e9gica de Bitcoin"},"content":{"rendered":"<p>Pensilvania ha tomado la delantera en los debates sobre la inclusi\u00f3n de Bitcoin como reserva de valor en Estados Unidos. Representantes de la C\u00e1mara del estado han presentado un proyecto de ley que propone la creaci\u00f3n de una reserva estrat\u00e9gica de BTC.<\/p>\n<p>Esta iniciativa surge en medio del regreso de Donald Trump a la presidencia, lo que ha reavivado las discusiones sobre la posibilidad de una reserva nacional de la criptomoneda.<\/p>\n<p>El proyecto propone que el Tesoro estatal pueda invertir hasta un 10% de fondos como el General Fund, el Rainy Day Fund y el State Investment Fund en Bitcoin.<\/p>\n<p>Si se aprueba, el estado podr\u00eda destinar hasta 970 millones de d\u00f3lares (aproximadamente 900 millones de euros) solo del General Fund para la compra de la criptomoneda. La justificaci\u00f3n legislativa resalta la necesidad de proteger el poder adquisitivo de Pensilvania frente a la inflaci\u00f3n, que ha reducido la capacidad de consumo del estado en casi un 20% en los \u00faltimos cuatro a\u00f1os.<\/p>\n<ul>\n<li>Lee tambi\u00e9n: <a href=\"https:\/\/www.criptofacil.com\/es\/nueva-plataforma-de-tether-permitira-la-tokenizacion-de-cualquier-activo\/\">Nueva plataforma de Tether permitir\u00e1 la tokenizaci\u00f3n de cualquier activo<\/a><\/li>\n<\/ul>\n<h2>Bitcoin como soluci\u00f3n contra la inflaci\u00f3n<\/h2>\n<p>En los \u00faltimos a\u00f1os, Bitcoin ha demostrado un crecimiento significativo. Mientras que la inflaci\u00f3n en EE. UU. alcanz\u00f3 el 9,1% en junio de 2022, cayendo a un 2,4% en septiembre de 2024, la criptomoneda ha registrado una valorizaci\u00f3n del 289%. El BTC subi\u00f3 de 22.900 d\u00f3lares (aproximadamente 21.500 euros) a m\u00e1s de 93.000 d\u00f3lares (unos 87.000 euros) este mes.<\/p>\n<p>Para los legisladores republicanos Mike Cabell y Aaron Kaufer, que lideran el proyecto en Pensilvania, esta valorizaci\u00f3n ofrece una soluci\u00f3n prometedora para enfrentar la devaluaci\u00f3n del d\u00f3lar.<\/p>\n<p>\u201cLa volatilidad de Bitcoin es real, pero tambi\u00e9n lo es su capacidad para superar la inflaci\u00f3n con el tiempo. Necesitamos alternativas que ofrezcan estabilidad en tiempos econ\u00f3micos inciertos\u201d, argumenta el memorando legislativo.<\/p>\n<p>Adem\u00e1s de la propuesta de Pensilvania, pol\u00edticos como la senadora Cynthia Lummis, de Wyoming, ya hab\u00edan sugerido una medida similar. Sin embargo, el proyecto perdi\u00f3 fuerza despu\u00e9s de la ca\u00edda del precio de la criptomoneda en agosto. Ahora, con Trump de vuelta en la Casa Blanca, el plan vuelve a cobrar relevancia.<\/p>\n<p>Trump, conocido por su apoyo al sector de las criptomonedas, considera que el momento es ideal para construir una base econ\u00f3mica m\u00e1s s\u00f3lida con Bitcoin.<\/p>\n<ul>\n<li>Lee tambi\u00e9n: <a href=\"https:\/\/www.criptofacil.com\/es\/policia-de-india-detiene-a-sospechoso-por-hackeo-a-la-exchange-de-criptomonedas-wazirx\/\">Polic\u00eda de India detiene a sospechoso por hackeo a la exchange de criptomonedas WazirX<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Pensilvania ha tomado la delantera en los debates sobre la inclusi\u00f3n de Bitcoin como reserva de valor en Estados Unidos. Representantes de la C\u00e1mara del estado han presentado un proyecto de ley que propone la creaci\u00f3n de una reserva estrat\u00e9gica de BTC. Esta iniciativa surge en medio del regreso de Donald Trump a la presidencia, [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":5783,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1796],"tags":[1781,1782,1789,1798,1825,1777,1816,1758],"class_list":["post-5782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-bitcoin","tag-btc","tag-donald-trump","tag-economia","tag-ee-uu","tag-estados-unidos","tag-super-titular","tag-titular"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pensilvania se adelanta a Trump y propone la creaci\u00f3n de una reserva estrat\u00e9gica de Bitcoin<\/title>\n<meta name=\"description\" content=\"Pensilvania ha tomado la delantera en los debates sobre la inclusi\u00f3n de Bitcoin como reserva de valor en Estados Unidos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pensilvania se adelanta a Trump y propone la creaci\u00f3n de una reserva estrat\u00e9gica de Bitcoin\" \/>\n<meta property=\"og:description\" content=\"Pensilvania ha tomado la delantera en los debates sobre la inclusi\u00f3n de Bitcoin como reserva de valor en Estados Unidos\" \/>\n<meta property=\"og:site_name\" content=\"CriptoF\u00e1cil Espa\u00f1ol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/criptomoedasfacil\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-16T14:00:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/11\/pensilvania-se-adianta-a-trump-e-propoe-reserva-btc-1536x806-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"806\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cassio Gusson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@criptofacil\" \/>\n<meta name=\"twitter:site\" content=\"@criptofacil\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cassio Gusson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/\"},\"author\":{\"name\":\"Cassio Gusson\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/2f9689f2b7291a5cceccd9685315d681\"},\"headline\":\"Pensilvania se adelanta a Trump y propone la creaci\u00f3n de una reserva estrat\u00e9gica de Bitcoin\",\"datePublished\":\"2024-11-16T14:00:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/\"},\"wordCount\":431,\"publisher\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/11\/pensilvania-se-adianta-a-trump-e-propoe-reserva-btc-1536x806-1.jpg\",\"keywords\":[\"Bitcoin\",\"BTC\",\"Donald Trump\",\"Econom\u00eda\",\"EE.UU\",\"Estados Unidos\",\"Super Titular\",\"Titular\"],\"articleSection\":[\"Econom\u00eda\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.criptofacil.com\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/\",\"url\":\"https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/\",\"name\":\"Pensilvania se adelanta a Trump y propone la creaci\u00f3n de una reserva estrat\u00e9gica de Bitcoin\",\"isPartOf\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/11\/pensilvania-se-adianta-a-trump-e-propoe-reserva-btc-1536x806-1.jpg\",\"datePublished\":\"2024-11-16T14:00:05+00:00\",\"description\":\"Pensilvania ha tomado la delantera en los debates sobre la inclusi\u00f3n de Bitcoin como reserva de valor en Estados Unidos\",\"breadcrumb\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/#primaryimage\",\"url\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/11\/pensilvania-se-adianta-a-trump-e-propoe-reserva-btc-1536x806-1.jpg\",\"contentUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/11\/pensilvania-se-adianta-a-trump-e-propoe-reserva-btc-1536x806-1.jpg\",\"width\":1536,\"height\":806,\"caption\":\"Pensilvania se adelanta a Trump y propone la creaci\u00f3n de una reserva estrat\u00e9gica de Bitcoin\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.criptofacil.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pensilvania se adelanta a Trump y propone la creaci\u00f3n de una reserva estrat\u00e9gica de Bitcoin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#website\",\"url\":\"https:\/\/www.criptofacil.com\/es\/\",\"name\":\"CriptoF\u00e1cil Espa\u00f1ol\",\"description\":\"Noticias sobre Bitcoin, Criptomonedas, DeFi, NFT, Web3 y Blockchain\",\"publisher\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#organization\"},\"alternateName\":\"CriptoF\u00e1cil\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.criptofacil.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#organization\",\"name\":\"CriptoF\u00e1cil\",\"url\":\"https:\/\/www.criptofacil.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png\",\"contentUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png\",\"width\":424,\"height\":104,\"caption\":\"CriptoF\u00e1cil\"},\"image\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/criptomoedasfacil\",\"https:\/\/x.com\/criptofacil\",\"https:\/\/youtube.com\/channel\/UCak-HWmXEqeC3KOjTN9Fr-Q?si=lWaoQK8jh5CRg1qt\",\"https:\/\/www.instagram.com\/criptofacil\/\",\"https:\/\/www.linkedin.com\/company\/criptofacil\/\",\"https:\/\/t.me\/criptomoedasfacil\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/2f9689f2b7291a5cceccd9685315d681\",\"name\":\"Cassio Gusson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ab0c8f1d9f613e8ae33731332feb0b1bc8860571d0d49118f9fe63403adc37cd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ab0c8f1d9f613e8ae33731332feb0b1bc8860571d0d49118f9fe63403adc37cd?s=96&d=mm&r=g\",\"caption\":\"Cassio Gusson\"},\"description\":\"C\u00e1ssio Gusson \u00e9 jornalista h\u00e1 mais de 20 anos com mais de 10 anos de experi\u00eancia no mercado de criptomoedas. \u00c9 formado em jornalismo pela FACCAMP e com p\u00f3s-gradua\u00e7\u00e3o em Globaliza\u00e7\u00e3o e Cultura. Ao longo de sua carreira entrevistou grandes personalidades como Adam Back, Bill Clinton, Henrique Meirelles, entre outros. Al\u00e9m de participar de importantes f\u00f3runs multilaterais como G20 e FMI. C\u00e1ssio migrou do poder p\u00fablico para o setor de blockchain e criptomoedas por acreditar no potencial transformador desta tecnologia para moldar o novo futuro da economia digital.\",\"sameAs\":[\"http:\/\/www.criptomoedasfacil.com\",\"https:\/\/www.linkedin.com\/in\/cassio-gusson-440ab7177\/\"],\"url\":\"https:\/\/www.criptofacil.com\/es\/author\/cassio-gusson\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pensilvania se adelanta a Trump y propone la creaci\u00f3n de una reserva estrat\u00e9gica de Bitcoin","description":"Pensilvania ha tomado la delantera en los debates sobre la inclusi\u00f3n de Bitcoin como reserva de valor en Estados Unidos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/","og_locale":"es_ES","og_type":"article","og_title":"Pensilvania se adelanta a Trump y propone la creaci\u00f3n de una reserva estrat\u00e9gica de Bitcoin","og_description":"Pensilvania ha tomado la delantera en los debates sobre la inclusi\u00f3n de Bitcoin como reserva de valor en Estados Unidos","og_site_name":"CriptoF\u00e1cil Espa\u00f1ol","article_publisher":"https:\/\/www.facebook.com\/criptomoedasfacil","article_published_time":"2024-11-16T14:00:05+00:00","og_image":[{"width":1536,"height":806,"url":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/11\/pensilvania-se-adianta-a-trump-e-propoe-reserva-btc-1536x806-1.jpg","type":"image\/jpeg"}],"author":"Cassio Gusson","twitter_card":"summary_large_image","twitter_creator":"@criptofacil","twitter_site":"@criptofacil","twitter_misc":{"Written by":"Cassio Gusson","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/#article","isPartOf":{"@id":"https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/"},"author":{"name":"Cassio Gusson","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/2f9689f2b7291a5cceccd9685315d681"},"headline":"Pensilvania se adelanta a Trump y propone la creaci\u00f3n de una reserva estrat\u00e9gica de Bitcoin","datePublished":"2024-11-16T14:00:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/"},"wordCount":431,"publisher":{"@id":"https:\/\/www.criptofacil.com\/es\/#organization"},"image":{"@id":"https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/11\/pensilvania-se-adianta-a-trump-e-propoe-reserva-btc-1536x806-1.jpg","keywords":["Bitcoin","BTC","Donald Trump","Econom\u00eda","EE.UU","Estados Unidos","Super Titular","Titular"],"articleSection":["Econom\u00eda"],"inLanguage":"es","copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.criptofacil.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/","url":"https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/","name":"Pensilvania se adelanta a Trump y propone la creaci\u00f3n de una reserva estrat\u00e9gica de Bitcoin","isPartOf":{"@id":"https:\/\/www.criptofacil.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/#primaryimage"},"image":{"@id":"https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/11\/pensilvania-se-adianta-a-trump-e-propoe-reserva-btc-1536x806-1.jpg","datePublished":"2024-11-16T14:00:05+00:00","description":"Pensilvania ha tomado la delantera en los debates sobre la inclusi\u00f3n de Bitcoin como reserva de valor en Estados Unidos","breadcrumb":{"@id":"https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/#primaryimage","url":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/11\/pensilvania-se-adianta-a-trump-e-propoe-reserva-btc-1536x806-1.jpg","contentUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/11\/pensilvania-se-adianta-a-trump-e-propoe-reserva-btc-1536x806-1.jpg","width":1536,"height":806,"caption":"Pensilvania se adelanta a Trump y propone la creaci\u00f3n de una reserva estrat\u00e9gica de Bitcoin"},{"@type":"BreadcrumbList","@id":"https:\/\/www.criptofacil.com\/es\/pensilvania-se-adelanta-a-trump-y-propone-la-creacion-de-una-reserva-estrategica-de-bitcoin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.criptofacil.com\/es\/"},{"@type":"ListItem","position":2,"name":"Pensilvania se adelanta a Trump y propone la creaci\u00f3n de una reserva estrat\u00e9gica de Bitcoin"}]},{"@type":"WebSite","@id":"https:\/\/www.criptofacil.com\/es\/#website","url":"https:\/\/www.criptofacil.com\/es\/","name":"CriptoF\u00e1cil Espa\u00f1ol","description":"Noticias sobre Bitcoin, Criptomonedas, DeFi, NFT, Web3 y Blockchain","publisher":{"@id":"https:\/\/www.criptofacil.com\/es\/#organization"},"alternateName":"CriptoF\u00e1cil","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.criptofacil.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.criptofacil.com\/es\/#organization","name":"CriptoF\u00e1cil","url":"https:\/\/www.criptofacil.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png","contentUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png","width":424,"height":104,"caption":"CriptoF\u00e1cil"},"image":{"@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/criptomoedasfacil","https:\/\/x.com\/criptofacil","https:\/\/youtube.com\/channel\/UCak-HWmXEqeC3KOjTN9Fr-Q?si=lWaoQK8jh5CRg1qt","https:\/\/www.instagram.com\/criptofacil\/","https:\/\/www.linkedin.com\/company\/criptofacil\/","https:\/\/t.me\/criptomoedasfacil"]},{"@type":"Person","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/2f9689f2b7291a5cceccd9685315d681","name":"Cassio Gusson","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ab0c8f1d9f613e8ae33731332feb0b1bc8860571d0d49118f9fe63403adc37cd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab0c8f1d9f613e8ae33731332feb0b1bc8860571d0d49118f9fe63403adc37cd?s=96&d=mm&r=g","caption":"Cassio Gusson"},"description":"C\u00e1ssio Gusson \u00e9 jornalista h\u00e1 mais de 20 anos com mais de 10 anos de experi\u00eancia no mercado de criptomoedas. \u00c9 formado em jornalismo pela FACCAMP e com p\u00f3s-gradua\u00e7\u00e3o em Globaliza\u00e7\u00e3o e Cultura. Ao longo de sua carreira entrevistou grandes personalidades como Adam Back, Bill Clinton, Henrique Meirelles, entre outros. Al\u00e9m de participar de importantes f\u00f3runs multilaterais como G20 e FMI. C\u00e1ssio migrou do poder p\u00fablico para o setor de blockchain e criptomoedas por acreditar no potencial transformador desta tecnologia para moldar o novo futuro da economia digital.","sameAs":["http:\/\/www.criptomoedasfacil.com","https:\/\/www.linkedin.com\/in\/cassio-gusson-440ab7177\/"],"url":"https:\/\/www.criptofacil.com\/es\/author\/cassio-gusson\/"}]}},"_links":{"self":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts\/5782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/comments?post=5782"}],"version-history":[{"count":1,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts\/5782\/revisions"}],"predecessor-version":[{"id":5784,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts\/5782\/revisions\/5784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/media\/5783"}],"wp:attachment":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/media?parent=5782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/categories?post=5782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/tags?post=5782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}