{"id":4509,"date":"2024-10-24T22:00:29","date_gmt":"2024-10-24T22:00:29","guid":{"rendered":"https:\/\/www.criptofacil.com\/es\/?p=4509"},"modified":"2024-10-24T19:19:55","modified_gmt":"2024-10-24T19:19:55","slug":"ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp","status":"publish","type":"post","link":"https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/","title":{"rendered":"Ripple admite error al no contactar a la SEC antes de lanzar XRP"},"content":{"rendered":"<p>El CEO de Ripple Labs, Brad Garlinghouse, hizo una importante declaraci\u00f3n al afirmar que la empresa cometi\u00f3 un error al no consultar con la Comisi\u00f3n de Valores y Bolsa de los Estados Unidos (SEC) antes de lanzar el token XRP.<\/p>\n<p>Durante su participaci\u00f3n en la DC Fintech Week, el 23 de octubre, Garlinghouse admiti\u00f3 que la falta de un contacto inicial con los reguladores gener\u00f3 grandes desaf\u00edos para Ripple y para toda la industria de las criptomonedas.<\/p>\n<p>El ejecutivo destac\u00f3 que Ripple deber\u00eda haber iniciado un di\u00e1logo con la SEC desde los primeros d\u00edas del lanzamiento de XRP.<\/p>\n<p>\u201cMirando hacia atr\u00e1s, veo que cometimos un error al no involucrarnos antes. Ahora estamos tratando de recuperar el tiempo perdido\u201d, dijo el CEO.<\/p>\n<p>Adem\u00e1s, revel\u00f3 que en los \u00faltimos a\u00f1os ha intensificado sus viajes a Washington, D.C., en un intento de corregir este error. Ripple ha enfrentado una larga batalla judicial con la SEC, que acusa a la empresa de haber vendido XRP como un valor no registrado a inversores institucionales.<\/p>\n<p>Aunque una parte de la decisi\u00f3n eximi\u00f3 la venta de XRP al p\u00fablico en general de ser considerada un valor, la SEC ha apelado. Esto significa que la disputa a\u00fan no ha llegado a su fin.<\/p>\n<ul>\n<li>Lee tambi\u00e9n: <a href=\"https:\/\/www.criptofacil.com\/es\/trader-pierde-usd-500000-con-una-memecoin-en-menos-de-una-hora\/\">Trader pierde USD 500,000 con una memecoin en menos de una hora<\/a><\/li>\n<\/ul>\n<h2>Regulaci\u00f3n y desaf\u00edos para Ripple<\/h2>\n<p>Brad Garlinghouse tambi\u00e9n critic\u00f3 la postura del presidente de la SEC, Gary Gensler. El ejecutivo de Ripple calific\u00f3 la gesti\u00f3n de Gensler como una \u201crepresi\u00f3n\u201d a la industria de las criptomonedas.<\/p>\n<p>Seg\u00fan el CEO, Estados Unidos est\u00e1 rezagado en comparaci\u00f3n con otros pa\u00edses en la creaci\u00f3n de un entorno regulatorio claro para el sector cripto. Tambi\u00e9n culp\u00f3 a la senadora Elizabeth Warren por difundir desinformaci\u00f3n sobre el mercado de criptoactivos.<\/p>\n<p>A pesar de los desaf\u00edos legales, Garlinghouse reafirm\u00f3 que Ripple continuar\u00e1 luchando por la legitimidad de XRP en el mercado.<\/p>\n<p>\u201cParte de este esfuerzo incluye educar al p\u00fablico y a los reguladores sobre la seriedad del espacio cripto\u201d, explic\u00f3. Tambi\u00e9n destac\u00f3 que Ripple ha sido activa en donaciones pol\u00edticas, contribuyendo con casi 50 millones de d\u00f3lares para apoyar a candidatos a favor de las criptomonedas.<\/p>\n<p>Garlinghouse aprovech\u00f3 la ocasi\u00f3n para comentar sobre el creciente inter\u00e9s en los ETFs de criptomonedas. Seg\u00fan afirm\u00f3, la creaci\u00f3n de un ETF de XRP en Estados Unidos es inevitable. Adem\u00e1s, se\u00f1al\u00f3 que el \u00e9xito de los ETFs de Bitcoin ha demostrado la demanda de productos financieros basados en criptomonedas, tanto por inversores institucionales como minoristas.<\/p>\n<p>\u201cCreo que XRP tiene una comunidad comprometida y activa, tanto en EE.UU. como internacionalmente. Con el tiempo, veremos m\u00e1s y m\u00e1s participaci\u00f3n institucional en el sector cripto, y eso incluye a XRP\u201d, concluy\u00f3 Garlinghouse.<\/p>\n<ul>\n<li>Lee tambi\u00e9n: <a href=\"https:\/\/www.criptofacil.com\/es\/dinamarca-se-convierte-en-el-primer-pais-en-gravar-ganancias-no-realizadas-con-criptomonedas\/\">Dinamarca se convierte en el primer pa\u00eds en gravar ganancias no realizadas con criptomonedas<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>El CEO de Ripple Labs, Brad Garlinghouse, hizo una importante declaraci\u00f3n al afirmar que la empresa cometi\u00f3 un error al no consultar con la Comisi\u00f3n de Valores y Bolsa de los Estados Unidos (SEC) antes de lanzar el token XRP. Durante su participaci\u00f3n en la DC Fintech Week, el 23 de octubre, Garlinghouse admiti\u00f3 que [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":4510,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[1881,1880,1758,1882],"class_list":["post-4509","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-ripple","tag-sec","tag-titular","tag-xrp"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ripple admite error al no contactar a la SEC antes de lanzar XRP<\/title>\n<meta name=\"description\" content=\"El CEO de Ripple Labs, Brad Garlinghouse, hizo una importante declaraci\u00f3n al afirmar que la empresa cometi\u00f3 un error al no hablar con la SEC\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ripple admite error al no contactar a la SEC antes de lanzar XRP\" \/>\n<meta property=\"og:description\" content=\"El CEO de Ripple Labs, Brad Garlinghouse, hizo una importante declaraci\u00f3n al afirmar que la empresa cometi\u00f3 un error al no hablar con la SEC\" \/>\n<meta property=\"og:site_name\" content=\"CriptoF\u00e1cil Espa\u00f1ol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/criptomoedasfacil\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-24T22:00:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/10\/ex-ripple-campanha-politica-Kamala-Harris-1536x806-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"806\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cassio Gusson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@criptofacil\" \/>\n<meta name=\"twitter:site\" content=\"@criptofacil\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cassio Gusson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/\"},\"author\":{\"name\":\"Cassio Gusson\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/2f9689f2b7291a5cceccd9685315d681\"},\"headline\":\"Ripple admite error al no contactar a la SEC antes de lanzar XRP\",\"datePublished\":\"2024-10-24T22:00:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/\"},\"wordCount\":517,\"publisher\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/10\/ex-ripple-campanha-politica-Kamala-Harris-1536x806-1.jpg\",\"keywords\":[\"Ripple\",\"SEC\",\"Titular\",\"XRP\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.criptofacil.com\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/\",\"url\":\"https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/\",\"name\":\"Ripple admite error al no contactar a la SEC antes de lanzar XRP\",\"isPartOf\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/10\/ex-ripple-campanha-politica-Kamala-Harris-1536x806-1.jpg\",\"datePublished\":\"2024-10-24T22:00:29+00:00\",\"description\":\"El CEO de Ripple Labs, Brad Garlinghouse, hizo una importante declaraci\u00f3n al afirmar que la empresa cometi\u00f3 un error al no hablar con la SEC\",\"breadcrumb\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/#primaryimage\",\"url\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/10\/ex-ripple-campanha-politica-Kamala-Harris-1536x806-1.jpg\",\"contentUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/10\/ex-ripple-campanha-politica-Kamala-Harris-1536x806-1.jpg\",\"width\":1536,\"height\":806,\"caption\":\"Ripple admite error al no contactar a la SEC antes de lanzar XRP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.criptofacil.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ripple admite error al no contactar a la SEC antes de lanzar XRP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#website\",\"url\":\"https:\/\/www.criptofacil.com\/es\/\",\"name\":\"CriptoF\u00e1cil Espa\u00f1ol\",\"description\":\"Noticias sobre Bitcoin, Criptomonedas, DeFi, NFT, Web3 y Blockchain\",\"publisher\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#organization\"},\"alternateName\":\"CriptoF\u00e1cil\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.criptofacil.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#organization\",\"name\":\"CriptoF\u00e1cil\",\"url\":\"https:\/\/www.criptofacil.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png\",\"contentUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png\",\"width\":424,\"height\":104,\"caption\":\"CriptoF\u00e1cil\"},\"image\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/criptomoedasfacil\",\"https:\/\/x.com\/criptofacil\",\"https:\/\/youtube.com\/channel\/UCak-HWmXEqeC3KOjTN9Fr-Q?si=lWaoQK8jh5CRg1qt\",\"https:\/\/www.instagram.com\/criptofacil\/\",\"https:\/\/www.linkedin.com\/company\/criptofacil\/\",\"https:\/\/t.me\/criptomoedasfacil\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/2f9689f2b7291a5cceccd9685315d681\",\"name\":\"Cassio Gusson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ab0c8f1d9f613e8ae33731332feb0b1bc8860571d0d49118f9fe63403adc37cd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ab0c8f1d9f613e8ae33731332feb0b1bc8860571d0d49118f9fe63403adc37cd?s=96&d=mm&r=g\",\"caption\":\"Cassio Gusson\"},\"description\":\"C\u00e1ssio Gusson \u00e9 jornalista h\u00e1 mais de 20 anos com mais de 10 anos de experi\u00eancia no mercado de criptomoedas. \u00c9 formado em jornalismo pela FACCAMP e com p\u00f3s-gradua\u00e7\u00e3o em Globaliza\u00e7\u00e3o e Cultura. Ao longo de sua carreira entrevistou grandes personalidades como Adam Back, Bill Clinton, Henrique Meirelles, entre outros. Al\u00e9m de participar de importantes f\u00f3runs multilaterais como G20 e FMI. C\u00e1ssio migrou do poder p\u00fablico para o setor de blockchain e criptomoedas por acreditar no potencial transformador desta tecnologia para moldar o novo futuro da economia digital.\",\"sameAs\":[\"http:\/\/www.criptomoedasfacil.com\",\"https:\/\/www.linkedin.com\/in\/cassio-gusson-440ab7177\/\"],\"url\":\"https:\/\/www.criptofacil.com\/es\/author\/cassio-gusson\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ripple admite error al no contactar a la SEC antes de lanzar XRP","description":"El CEO de Ripple Labs, Brad Garlinghouse, hizo una importante declaraci\u00f3n al afirmar que la empresa cometi\u00f3 un error al no hablar con la SEC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/","og_locale":"es_ES","og_type":"article","og_title":"Ripple admite error al no contactar a la SEC antes de lanzar XRP","og_description":"El CEO de Ripple Labs, Brad Garlinghouse, hizo una importante declaraci\u00f3n al afirmar que la empresa cometi\u00f3 un error al no hablar con la SEC","og_site_name":"CriptoF\u00e1cil Espa\u00f1ol","article_publisher":"https:\/\/www.facebook.com\/criptomoedasfacil","article_published_time":"2024-10-24T22:00:29+00:00","og_image":[{"width":1536,"height":806,"url":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/10\/ex-ripple-campanha-politica-Kamala-Harris-1536x806-1.jpg","type":"image\/jpeg"}],"author":"Cassio Gusson","twitter_card":"summary_large_image","twitter_creator":"@criptofacil","twitter_site":"@criptofacil","twitter_misc":{"Written by":"Cassio Gusson","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/#article","isPartOf":{"@id":"https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/"},"author":{"name":"Cassio Gusson","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/2f9689f2b7291a5cceccd9685315d681"},"headline":"Ripple admite error al no contactar a la SEC antes de lanzar XRP","datePublished":"2024-10-24T22:00:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/"},"wordCount":517,"publisher":{"@id":"https:\/\/www.criptofacil.com\/es\/#organization"},"image":{"@id":"https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/#primaryimage"},"thumbnailUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/10\/ex-ripple-campanha-politica-Kamala-Harris-1536x806-1.jpg","keywords":["Ripple","SEC","Titular","XRP"],"articleSection":["Noticias"],"inLanguage":"es","copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.criptofacil.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/","url":"https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/","name":"Ripple admite error al no contactar a la SEC antes de lanzar XRP","isPartOf":{"@id":"https:\/\/www.criptofacil.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/#primaryimage"},"image":{"@id":"https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/#primaryimage"},"thumbnailUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/10\/ex-ripple-campanha-politica-Kamala-Harris-1536x806-1.jpg","datePublished":"2024-10-24T22:00:29+00:00","description":"El CEO de Ripple Labs, Brad Garlinghouse, hizo una importante declaraci\u00f3n al afirmar que la empresa cometi\u00f3 un error al no hablar con la SEC","breadcrumb":{"@id":"https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/#primaryimage","url":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/10\/ex-ripple-campanha-politica-Kamala-Harris-1536x806-1.jpg","contentUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/10\/ex-ripple-campanha-politica-Kamala-Harris-1536x806-1.jpg","width":1536,"height":806,"caption":"Ripple admite error al no contactar a la SEC antes de lanzar XRP"},{"@type":"BreadcrumbList","@id":"https:\/\/www.criptofacil.com\/es\/ripple-admite-error-al-no-contactar-a-la-sec-antes-de-lanzar-xrp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.criptofacil.com\/es\/"},{"@type":"ListItem","position":2,"name":"Ripple admite error al no contactar a la SEC antes de lanzar XRP"}]},{"@type":"WebSite","@id":"https:\/\/www.criptofacil.com\/es\/#website","url":"https:\/\/www.criptofacil.com\/es\/","name":"CriptoF\u00e1cil Espa\u00f1ol","description":"Noticias sobre Bitcoin, Criptomonedas, DeFi, NFT, Web3 y Blockchain","publisher":{"@id":"https:\/\/www.criptofacil.com\/es\/#organization"},"alternateName":"CriptoF\u00e1cil","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.criptofacil.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.criptofacil.com\/es\/#organization","name":"CriptoF\u00e1cil","url":"https:\/\/www.criptofacil.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png","contentUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png","width":424,"height":104,"caption":"CriptoF\u00e1cil"},"image":{"@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/criptomoedasfacil","https:\/\/x.com\/criptofacil","https:\/\/youtube.com\/channel\/UCak-HWmXEqeC3KOjTN9Fr-Q?si=lWaoQK8jh5CRg1qt","https:\/\/www.instagram.com\/criptofacil\/","https:\/\/www.linkedin.com\/company\/criptofacil\/","https:\/\/t.me\/criptomoedasfacil"]},{"@type":"Person","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/2f9689f2b7291a5cceccd9685315d681","name":"Cassio Gusson","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ab0c8f1d9f613e8ae33731332feb0b1bc8860571d0d49118f9fe63403adc37cd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab0c8f1d9f613e8ae33731332feb0b1bc8860571d0d49118f9fe63403adc37cd?s=96&d=mm&r=g","caption":"Cassio Gusson"},"description":"C\u00e1ssio Gusson \u00e9 jornalista h\u00e1 mais de 20 anos com mais de 10 anos de experi\u00eancia no mercado de criptomoedas. \u00c9 formado em jornalismo pela FACCAMP e com p\u00f3s-gradua\u00e7\u00e3o em Globaliza\u00e7\u00e3o e Cultura. Ao longo de sua carreira entrevistou grandes personalidades como Adam Back, Bill Clinton, Henrique Meirelles, entre outros. Al\u00e9m de participar de importantes f\u00f3runs multilaterais como G20 e FMI. C\u00e1ssio migrou do poder p\u00fablico para o setor de blockchain e criptomoedas por acreditar no potencial transformador desta tecnologia para moldar o novo futuro da economia digital.","sameAs":["http:\/\/www.criptomoedasfacil.com","https:\/\/www.linkedin.com\/in\/cassio-gusson-440ab7177\/"],"url":"https:\/\/www.criptofacil.com\/es\/author\/cassio-gusson\/"}]}},"_links":{"self":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts\/4509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/comments?post=4509"}],"version-history":[{"count":1,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts\/4509\/revisions"}],"predecessor-version":[{"id":4511,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts\/4509\/revisions\/4511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/media\/4510"}],"wp:attachment":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/media?parent=4509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/categories?post=4509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/tags?post=4509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}