{"id":2809,"date":"2024-09-28T17:00:18","date_gmt":"2024-09-28T17:00:18","guid":{"rendered":"https:\/\/www.criptofacil.com\/es\/?p=2809"},"modified":"2024-09-28T01:36:50","modified_gmt":"2024-09-28T01:36:50","slug":"celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens","status":"publish","type":"post","link":"https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/","title":{"rendered":"Celestia (TIA) mantiene su alza a pesar del desbloqueo de US$ 2 mil millones en tokens"},"content":{"rendered":"<p>Celestia (TIA) sigue en una trayectoria ascendente, incluso con el desbloqueo inminente de US$ 1,1 mil millones en tokens programado para el 31 de octubre de 2024. Este movimiento es parte de un desbloqueo total de casi US$ 2 mil millones en el mercado de criptomonedas durante el mes de octubre.<\/p>\n<p>Con la liberaci\u00f3n de 175,75 millones de tokens, destinados a contribuyentes iniciales, equipos de desarrollo e inversores de varias rondas, el impacto en el mercado se ha convertido en una preocupaci\u00f3n tanto para inversores como para analistas.<\/p>\n<p>Otros proyectos, como Cheelee, que tambi\u00e9n tiene un gran desbloqueo de US$ 300 millones en tokens el 10 de octubre, enfrentan desaf\u00edos de estabilidad.<\/p>\n<p>El precio del token CHEEL, por ejemplo, cay\u00f3 significativamente despu\u00e9s de una suspensi\u00f3n temporal de retiros, lo que gener\u00f3 dudas sobre su capacidad para mantener su valor.<\/p>\n<p>Sin embargo, el token TIA de Celestia parece no verse afectado por estas tendencias negativas, presentando un ligero aumento del 2,23%, cotizando a US$ 6,41. Aunque sigue por debajo de su m\u00e1ximo hist\u00f3rico de US$ 20,91 en febrero de 2024, la resiliencia del TIA impresiona a los expertos.<\/p>\n<ul>\n<li>Lee tambi\u00e9n: <a href=\"https:\/\/www.criptofacil.com\/es\/paypal-permitira-comprar-vender-y-mantener-criptos-a-cuentas-comerciales\/\">Paypal permitir\u00e1 comprar, vender y mantener criptos a cuentas comerciales<\/a><\/li>\n<\/ul>\n<h2><strong>Celestia (TIA) resiste los desbloqueos<\/strong><\/h2>\n<p>Este desbloqueo no solo marca un momento crucial para Celestia, sino que tambi\u00e9n puede moldear el futuro de la red. La popularidad del proyecto ha crecido sustancialmente desde finales de 2023, a medida que su enfoque modular ha atra\u00eddo la atenci\u00f3n de la comunidad cripto.<\/p>\n<p>Con esto, el mercado de criptomonedas en general se prepara para uno de los meses m\u00e1s importantes del a\u00f1o, ya que la absorci\u00f3n de estos activos desbloqueados puede influir directamente en la liquidez y el comportamiento de los precios.<\/p>\n<p>Otros grandes nombres tambi\u00e9n est\u00e1n en la mira de los inversores en octubre. Aptos, Starknet, Arbitrum, ImmutableX y Axie Infinity liberar\u00e1n un total adicional de US$ 600 millones en tokens.<\/p>\n<p>Aptos, por ejemplo, desbloquear\u00e1 US$ 90 millones el 12 de octubre, destac\u00e1ndose entre los principales lanzamientos del mes.<\/p>\n<p>Este per\u00edodo de desbloqueos masivos, sin embargo, no garantiza una valorizaci\u00f3n inmediata. Muchos inversores est\u00e1n a la espera de ver c\u00f3mo reaccionar\u00e1 el mercado ante esta inyecci\u00f3n repentina de liquidez, especialmente en un escenario de alta volatilidad.<\/p>\n<ul>\n<li>Lee tambi\u00e9n: <a href=\"https:\/\/www.criptofacil.com\/es\/memecoins-en-auge-dogecoin-shiba-inu-pepe-floki-haz-stake-con-888-apy\/\">Auge de las Memecoins: Dogecoin, Shiba Inu, PEPE y FLOKI \u2013 Obt\u00e9n hasta un 888% APY haciendo stake<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Celestia (TIA) sigue en una trayectoria ascendente, incluso con el desbloqueo inminente de US$ 1,1 mil millones en tokens programado para el 31 de octubre de 2024. Este movimiento es parte de un desbloqueo total de casi US$ 2 mil millones en el mercado de criptomonedas durante el mes de octubre. Con la liberaci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":2810,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1760],"tags":[1793,1766,2078,1779,1771,1758],"class_list":["post-2809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado","tag-altcoin","tag-analisis","tag-celestia","tag-criptoactivos","tag-criptomonedas","tag-titular"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Celestia (TIA) mantiene su alza a pesar del desbloqueo de US$ 2 mil millones en tokens<\/title>\n<meta name=\"description\" content=\"Celestia (TIA) sigue en una trayectoria ascendente, incluso con el desbloqueo inminente de US$ 1,1 mil millones en tokens\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Celestia (TIA) mantiene su alza a pesar del desbloqueo de US$ 2 mil millones en tokens\" \/>\n<meta property=\"og:description\" content=\"Celestia (TIA) sigue en una trayectoria ascendente, incluso con el desbloqueo inminente de US$ 1,1 mil millones en tokens\" \/>\n<meta property=\"og:site_name\" content=\"CriptoF\u00e1cil Espa\u00f1ol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/criptomoedasfacil\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-28T17:00:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/celestia-primeiro-grande-desbloqueio-1536x806-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"806\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cassio Gusson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@criptofacil\" \/>\n<meta name=\"twitter:site\" content=\"@criptofacil\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cassio Gusson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/\"},\"author\":{\"name\":\"Cassio Gusson\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/2f9689f2b7291a5cceccd9685315d681\"},\"headline\":\"Celestia (TIA) mantiene su alza a pesar del desbloqueo de US$ 2 mil millones en tokens\",\"datePublished\":\"2024-09-28T17:00:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/\"},\"wordCount\":417,\"publisher\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/celestia-primeiro-grande-desbloqueio-1536x806-1.jpg\",\"keywords\":[\"Altcoin\",\"Analisis\",\"Celestia\",\"Criptoactivos\",\"Criptomonedas\",\"Titular\"],\"articleSection\":[\"Mercado\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.criptofacil.com\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/\",\"url\":\"https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/\",\"name\":\"Celestia (TIA) mantiene su alza a pesar del desbloqueo de US$ 2 mil millones en tokens\",\"isPartOf\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/celestia-primeiro-grande-desbloqueio-1536x806-1.jpg\",\"datePublished\":\"2024-09-28T17:00:18+00:00\",\"description\":\"Celestia (TIA) sigue en una trayectoria ascendente, incluso con el desbloqueo inminente de US$ 1,1 mil millones en tokens\",\"breadcrumb\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/#primaryimage\",\"url\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/celestia-primeiro-grande-desbloqueio-1536x806-1.jpg\",\"contentUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/celestia-primeiro-grande-desbloqueio-1536x806-1.jpg\",\"width\":1536,\"height\":806,\"caption\":\"Celestia (TIA) mantiene su alza a pesar del desbloqueo de US$ 2 mil millones en tokens\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.criptofacil.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Celestia (TIA) mantiene su alza a pesar del desbloqueo de US$ 2 mil millones en tokens\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#website\",\"url\":\"https:\/\/www.criptofacil.com\/es\/\",\"name\":\"CriptoF\u00e1cil Espa\u00f1ol\",\"description\":\"Noticias sobre Bitcoin, Criptomonedas, DeFi, NFT, Web3 y Blockchain\",\"publisher\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#organization\"},\"alternateName\":\"CriptoF\u00e1cil\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.criptofacil.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#organization\",\"name\":\"CriptoF\u00e1cil\",\"url\":\"https:\/\/www.criptofacil.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png\",\"contentUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png\",\"width\":424,\"height\":104,\"caption\":\"CriptoF\u00e1cil\"},\"image\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/criptomoedasfacil\",\"https:\/\/x.com\/criptofacil\",\"https:\/\/youtube.com\/channel\/UCak-HWmXEqeC3KOjTN9Fr-Q?si=lWaoQK8jh5CRg1qt\",\"https:\/\/www.instagram.com\/criptofacil\/\",\"https:\/\/www.linkedin.com\/company\/criptofacil\/\",\"https:\/\/t.me\/criptomoedasfacil\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/2f9689f2b7291a5cceccd9685315d681\",\"name\":\"Cassio Gusson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ab0c8f1d9f613e8ae33731332feb0b1bc8860571d0d49118f9fe63403adc37cd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ab0c8f1d9f613e8ae33731332feb0b1bc8860571d0d49118f9fe63403adc37cd?s=96&d=mm&r=g\",\"caption\":\"Cassio Gusson\"},\"description\":\"C\u00e1ssio Gusson \u00e9 jornalista h\u00e1 mais de 20 anos com mais de 10 anos de experi\u00eancia no mercado de criptomoedas. \u00c9 formado em jornalismo pela FACCAMP e com p\u00f3s-gradua\u00e7\u00e3o em Globaliza\u00e7\u00e3o e Cultura. Ao longo de sua carreira entrevistou grandes personalidades como Adam Back, Bill Clinton, Henrique Meirelles, entre outros. Al\u00e9m de participar de importantes f\u00f3runs multilaterais como G20 e FMI. C\u00e1ssio migrou do poder p\u00fablico para o setor de blockchain e criptomoedas por acreditar no potencial transformador desta tecnologia para moldar o novo futuro da economia digital.\",\"sameAs\":[\"http:\/\/www.criptomoedasfacil.com\",\"https:\/\/www.linkedin.com\/in\/cassio-gusson-440ab7177\/\"],\"url\":\"https:\/\/www.criptofacil.com\/es\/author\/cassio-gusson\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Celestia (TIA) mantiene su alza a pesar del desbloqueo de US$ 2 mil millones en tokens","description":"Celestia (TIA) sigue en una trayectoria ascendente, incluso con el desbloqueo inminente de US$ 1,1 mil millones en tokens","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/","og_locale":"es_ES","og_type":"article","og_title":"Celestia (TIA) mantiene su alza a pesar del desbloqueo de US$ 2 mil millones en tokens","og_description":"Celestia (TIA) sigue en una trayectoria ascendente, incluso con el desbloqueo inminente de US$ 1,1 mil millones en tokens","og_site_name":"CriptoF\u00e1cil Espa\u00f1ol","article_publisher":"https:\/\/www.facebook.com\/criptomoedasfacil","article_published_time":"2024-09-28T17:00:18+00:00","og_image":[{"width":1536,"height":806,"url":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/celestia-primeiro-grande-desbloqueio-1536x806-1.jpg","type":"image\/jpeg"}],"author":"Cassio Gusson","twitter_card":"summary_large_image","twitter_creator":"@criptofacil","twitter_site":"@criptofacil","twitter_misc":{"Written by":"Cassio Gusson","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/#article","isPartOf":{"@id":"https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/"},"author":{"name":"Cassio Gusson","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/2f9689f2b7291a5cceccd9685315d681"},"headline":"Celestia (TIA) mantiene su alza a pesar del desbloqueo de US$ 2 mil millones en tokens","datePublished":"2024-09-28T17:00:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/"},"wordCount":417,"publisher":{"@id":"https:\/\/www.criptofacil.com\/es\/#organization"},"image":{"@id":"https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/#primaryimage"},"thumbnailUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/celestia-primeiro-grande-desbloqueio-1536x806-1.jpg","keywords":["Altcoin","Analisis","Celestia","Criptoactivos","Criptomonedas","Titular"],"articleSection":["Mercado"],"inLanguage":"es","copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.criptofacil.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/","url":"https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/","name":"Celestia (TIA) mantiene su alza a pesar del desbloqueo de US$ 2 mil millones en tokens","isPartOf":{"@id":"https:\/\/www.criptofacil.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/#primaryimage"},"image":{"@id":"https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/#primaryimage"},"thumbnailUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/celestia-primeiro-grande-desbloqueio-1536x806-1.jpg","datePublished":"2024-09-28T17:00:18+00:00","description":"Celestia (TIA) sigue en una trayectoria ascendente, incluso con el desbloqueo inminente de US$ 1,1 mil millones en tokens","breadcrumb":{"@id":"https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/#primaryimage","url":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/celestia-primeiro-grande-desbloqueio-1536x806-1.jpg","contentUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/celestia-primeiro-grande-desbloqueio-1536x806-1.jpg","width":1536,"height":806,"caption":"Celestia (TIA) mantiene su alza a pesar del desbloqueo de US$ 2 mil millones en tokens"},{"@type":"BreadcrumbList","@id":"https:\/\/www.criptofacil.com\/es\/celestia-tia-mantiene-su-alza-a-pesar-del-desbloqueo-de-us-2-mil-millones-en-tokens\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.criptofacil.com\/es\/"},{"@type":"ListItem","position":2,"name":"Celestia (TIA) mantiene su alza a pesar del desbloqueo de US$ 2 mil millones en tokens"}]},{"@type":"WebSite","@id":"https:\/\/www.criptofacil.com\/es\/#website","url":"https:\/\/www.criptofacil.com\/es\/","name":"CriptoF\u00e1cil Espa\u00f1ol","description":"Noticias sobre Bitcoin, Criptomonedas, DeFi, NFT, Web3 y Blockchain","publisher":{"@id":"https:\/\/www.criptofacil.com\/es\/#organization"},"alternateName":"CriptoF\u00e1cil","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.criptofacil.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.criptofacil.com\/es\/#organization","name":"CriptoF\u00e1cil","url":"https:\/\/www.criptofacil.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png","contentUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png","width":424,"height":104,"caption":"CriptoF\u00e1cil"},"image":{"@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/criptomoedasfacil","https:\/\/x.com\/criptofacil","https:\/\/youtube.com\/channel\/UCak-HWmXEqeC3KOjTN9Fr-Q?si=lWaoQK8jh5CRg1qt","https:\/\/www.instagram.com\/criptofacil\/","https:\/\/www.linkedin.com\/company\/criptofacil\/","https:\/\/t.me\/criptomoedasfacil"]},{"@type":"Person","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/2f9689f2b7291a5cceccd9685315d681","name":"Cassio Gusson","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ab0c8f1d9f613e8ae33731332feb0b1bc8860571d0d49118f9fe63403adc37cd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab0c8f1d9f613e8ae33731332feb0b1bc8860571d0d49118f9fe63403adc37cd?s=96&d=mm&r=g","caption":"Cassio Gusson"},"description":"C\u00e1ssio Gusson \u00e9 jornalista h\u00e1 mais de 20 anos com mais de 10 anos de experi\u00eancia no mercado de criptomoedas. \u00c9 formado em jornalismo pela FACCAMP e com p\u00f3s-gradua\u00e7\u00e3o em Globaliza\u00e7\u00e3o e Cultura. Ao longo de sua carreira entrevistou grandes personalidades como Adam Back, Bill Clinton, Henrique Meirelles, entre outros. Al\u00e9m de participar de importantes f\u00f3runs multilaterais como G20 e FMI. C\u00e1ssio migrou do poder p\u00fablico para o setor de blockchain e criptomoedas por acreditar no potencial transformador desta tecnologia para moldar o novo futuro da economia digital.","sameAs":["http:\/\/www.criptomoedasfacil.com","https:\/\/www.linkedin.com\/in\/cassio-gusson-440ab7177\/"],"url":"https:\/\/www.criptofacil.com\/es\/author\/cassio-gusson\/"}]}},"_links":{"self":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts\/2809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/comments?post=2809"}],"version-history":[{"count":1,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts\/2809\/revisions"}],"predecessor-version":[{"id":2811,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts\/2809\/revisions\/2811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/media\/2810"}],"wp:attachment":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/media?parent=2809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/categories?post=2809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/tags?post=2809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}