{"id":2376,"date":"2024-09-20T10:00:26","date_gmt":"2024-09-20T10:00:26","guid":{"rendered":"https:\/\/www.criptofacil.com\/es\/?p=2376"},"modified":"2024-09-19T20:24:17","modified_gmt":"2024-09-19T20:24:17","slug":"el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record","status":"publish","type":"post","link":"https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/","title":{"rendered":"El poder computacional de Bitcoin cae un 9,95% tras alcanzar una tasa de hash r\u00e9cord"},"content":{"rendered":"<p>El poder computacional de la red de Bitcoin registr\u00f3 una ca\u00edda del 9,95% despu\u00e9s de alcanzar un m\u00e1ximo hist\u00f3rico de 693 exahashes por segundo (EH\/s) a principios de septiembre de 2024.<\/p>\n<p>Esta reducci\u00f3n significativa en el hashrate ocurre solo nueve d\u00edas despu\u00e9s de que la red de Bitcoin alcanzara su pico de procesamiento, reflejando los desaf\u00edos econ\u00f3micos que enfrentan los mineros actualmente.<\/p>\n<p>El aumento en la dificultad de miner\u00eda, que subi\u00f3 un 3,58% despu\u00e9s del pico del hashrate, contribuy\u00f3 a la disminuci\u00f3n en el poder computacional de la red. La dificultad de miner\u00eda se ajusta peri\u00f3dicamente para garantizar que se minen nuevos bloques a una tasa constante, lo que aumenta la competencia entre los mineros.<\/p>\n<p>El 10 de septiembre, la red alcanz\u00f3 un nuevo r\u00e9cord de dificultad, lo que hizo que fuera m\u00e1s dif\u00edcil validar transacciones y crear nuevos bloques, presionando a\u00fan m\u00e1s la rentabilidad de los mineros. Este aumento en la dificultad, combinado con el cuarto halving de Bitcoin \u2014evento que redujo las recompensas por bloque de 6,25 BTC a 3,125 BTC\u2014 ha generado un panorama desafiante para la industria minera.<\/p>\n<p>Como resultado, los mineros que no cuentan con operaciones altamente eficientes est\u00e1n encontrando dificultades para mantenerse rentables, obligando a algunos a apagar sus m\u00e1quinas, lo que impacta directamente el hashrate global de la red.<\/p>\n<ul>\n<li>Lee tambi\u00e9n: <a href=\"https:\/\/www.criptofacil.com\/es\/fundador-de-cardano-charles-hoskinson-se-reunira-con-milei-para-discutir-el-futuro-de-blockchain-en-argentina\/\">Fundador de Cardano, Charles Hoskinson, se reunir\u00e1 con Milei para discutir el futuro de blockchain en Argentina<\/a><\/li>\n<\/ul>\n<h2>Poder computacional de Bitcoin<\/h2>\n<p>Adem\u00e1s de la reducci\u00f3n de las recompensas, las tarifas de transacci\u00f3n tambi\u00e9n se encuentran en niveles hist\u00f3ricamente bajos, lo que agrava a\u00fan m\u00e1s la situaci\u00f3n. Datos recientes de mempool.space muestran que una tarifa de prioridad alta cuesta solo 3 satoshis por byte virtual (sat\/vB), equivalente a aproximadamente $0,25.<\/p>\n<p>Con el precio de Bitcoin fluctuando en niveles m\u00e1s bajos en los \u00faltimos meses, el valor generado por petahash por segundo (PH\/s) por d\u00eda tambi\u00e9n ha ca\u00eddo dr\u00e1sticamente.<\/p>\n<p>Esta disminuci\u00f3n en los ingresos globales de los mineros, combinada con el aumento de la dificultad de miner\u00eda, crea una barrera para los participantes m\u00e1s peque\u00f1os y menos eficientes en el mercado, que no pueden mantenerse al d\u00eda con los altos costos operativos. Hasta ahora, la red de Bitcoin ha perdido aproximadamente 69 EH\/s desde su pico hist\u00f3rico, con el hashrate actual situado en 624 EH\/s.<\/p>\n<p>La ca\u00edda en el hashrate de Bitcoin plantea preocupaciones sobre la concentraci\u00f3n del poder minero. Al disminuir la rentabilidad, las operaciones mineras menos eficientes se ven forzadas a salir del mercado, lo que abre espacio para que grandes mineros con infraestructura avanzada dominen la red.<\/p>\n<ul>\n<li>Lee tambi\u00e9n: <a href=\"https:\/\/www.criptofacil.com\/es\/competencia-de-hackathon-llevara-a-los-mejores-desarrolladores-de-bitcoin-a-argentina\/\">Competencia de Hackathon llevar\u00e1 a los mejores desarrolladores de Bitcoin a Argentina<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>El poder computacional de la red de Bitcoin registr\u00f3 una ca\u00edda del 9,95% despu\u00e9s de alcanzar un m\u00e1ximo hist\u00f3rico de 693 exahashes por segundo (EH\/s) a principios de septiembre de 2024. Esta reducci\u00f3n significativa en el hashrate ocurre solo nueve d\u00edas despu\u00e9s de que la red de Bitcoin alcanzara su pico de procesamiento, reflejando los [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":2377,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1760],"tags":[1781,1771,1767,1758],"class_list":["post-2376","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado","tag-bitcoin","tag-criptomonedas","tag-mercado","tag-titular"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El poder computacional de Bitcoin cae un 9,95% tras alcanzar una tasa de hash r\u00e9cord<\/title>\n<meta name=\"description\" content=\"El poder computacional de la red de Bitcoin registr\u00f3 una ca\u00edda del 9,95% despu\u00e9s de alcanzar un r\u00e9cord hist\u00f3rico de 693 exahashes por segundo (EH\/s).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El poder computacional de Bitcoin cae un 9,95% tras alcanzar una tasa de hash r\u00e9cord\" \/>\n<meta property=\"og:description\" content=\"El poder computacional de la red de Bitcoin registr\u00f3 una ca\u00edda del 9,95% despu\u00e9s de alcanzar un r\u00e9cord hist\u00f3rico de 693 exahashes por segundo (EH\/s).\" \/>\n<meta property=\"og:site_name\" content=\"CriptoF\u00e1cil Espa\u00f1ol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/criptomoedasfacil\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-20T10:00:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/comprar-bitcoin.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1445\" \/>\n\t<meta property=\"og:image:height\" content=\"783\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Cassio Gusson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@criptofacil\" \/>\n<meta name=\"twitter:site\" content=\"@criptofacil\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cassio Gusson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/\"},\"author\":{\"name\":\"Cassio Gusson\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/2f9689f2b7291a5cceccd9685315d681\"},\"headline\":\"El poder computacional de Bitcoin cae un 9,95% tras alcanzar una tasa de hash r\u00e9cord\",\"datePublished\":\"2024-09-20T10:00:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/\"},\"wordCount\":494,\"publisher\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/comprar-bitcoin.png\",\"keywords\":[\"Bitcoin\",\"Criptomonedas\",\"Mercado\",\"Titular\"],\"articleSection\":[\"Mercado\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.criptofacil.com\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/\",\"url\":\"https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/\",\"name\":\"El poder computacional de Bitcoin cae un 9,95% tras alcanzar una tasa de hash r\u00e9cord\",\"isPartOf\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/comprar-bitcoin.png\",\"datePublished\":\"2024-09-20T10:00:26+00:00\",\"description\":\"El poder computacional de la red de Bitcoin registr\u00f3 una ca\u00edda del 9,95% despu\u00e9s de alcanzar un r\u00e9cord hist\u00f3rico de 693 exahashes por segundo (EH\/s).\",\"breadcrumb\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/#primaryimage\",\"url\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/comprar-bitcoin.png\",\"contentUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/comprar-bitcoin.png\",\"width\":1445,\"height\":783,\"caption\":\"El poder computacional de Bitcoin cae un 9,95% tras alcanzar una tasa de hash r\u00e9cord\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.criptofacil.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El poder computacional de Bitcoin cae un 9,95% tras alcanzar una tasa de hash r\u00e9cord\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#website\",\"url\":\"https:\/\/www.criptofacil.com\/es\/\",\"name\":\"CriptoF\u00e1cil Espa\u00f1ol\",\"description\":\"Noticias sobre Bitcoin, Criptomonedas, DeFi, NFT, Web3 y Blockchain\",\"publisher\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#organization\"},\"alternateName\":\"CriptoF\u00e1cil\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.criptofacil.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#organization\",\"name\":\"CriptoF\u00e1cil\",\"url\":\"https:\/\/www.criptofacil.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png\",\"contentUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png\",\"width\":424,\"height\":104,\"caption\":\"CriptoF\u00e1cil\"},\"image\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/criptomoedasfacil\",\"https:\/\/x.com\/criptofacil\",\"https:\/\/youtube.com\/channel\/UCak-HWmXEqeC3KOjTN9Fr-Q?si=lWaoQK8jh5CRg1qt\",\"https:\/\/www.instagram.com\/criptofacil\/\",\"https:\/\/www.linkedin.com\/company\/criptofacil\/\",\"https:\/\/t.me\/criptomoedasfacil\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/2f9689f2b7291a5cceccd9685315d681\",\"name\":\"Cassio Gusson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ab0c8f1d9f613e8ae33731332feb0b1bc8860571d0d49118f9fe63403adc37cd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ab0c8f1d9f613e8ae33731332feb0b1bc8860571d0d49118f9fe63403adc37cd?s=96&d=mm&r=g\",\"caption\":\"Cassio Gusson\"},\"description\":\"C\u00e1ssio Gusson \u00e9 jornalista h\u00e1 mais de 20 anos com mais de 10 anos de experi\u00eancia no mercado de criptomoedas. \u00c9 formado em jornalismo pela FACCAMP e com p\u00f3s-gradua\u00e7\u00e3o em Globaliza\u00e7\u00e3o e Cultura. Ao longo de sua carreira entrevistou grandes personalidades como Adam Back, Bill Clinton, Henrique Meirelles, entre outros. Al\u00e9m de participar de importantes f\u00f3runs multilaterais como G20 e FMI. C\u00e1ssio migrou do poder p\u00fablico para o setor de blockchain e criptomoedas por acreditar no potencial transformador desta tecnologia para moldar o novo futuro da economia digital.\",\"sameAs\":[\"http:\/\/www.criptomoedasfacil.com\",\"https:\/\/www.linkedin.com\/in\/cassio-gusson-440ab7177\/\"],\"url\":\"https:\/\/www.criptofacil.com\/es\/author\/cassio-gusson\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El poder computacional de Bitcoin cae un 9,95% tras alcanzar una tasa de hash r\u00e9cord","description":"El poder computacional de la red de Bitcoin registr\u00f3 una ca\u00edda del 9,95% despu\u00e9s de alcanzar un r\u00e9cord hist\u00f3rico de 693 exahashes por segundo (EH\/s).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/","og_locale":"es_ES","og_type":"article","og_title":"El poder computacional de Bitcoin cae un 9,95% tras alcanzar una tasa de hash r\u00e9cord","og_description":"El poder computacional de la red de Bitcoin registr\u00f3 una ca\u00edda del 9,95% despu\u00e9s de alcanzar un r\u00e9cord hist\u00f3rico de 693 exahashes por segundo (EH\/s).","og_site_name":"CriptoF\u00e1cil Espa\u00f1ol","article_publisher":"https:\/\/www.facebook.com\/criptomoedasfacil","article_published_time":"2024-09-20T10:00:26+00:00","og_image":[{"width":1445,"height":783,"url":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/comprar-bitcoin.png","type":"image\/png"}],"author":"Cassio Gusson","twitter_card":"summary_large_image","twitter_creator":"@criptofacil","twitter_site":"@criptofacil","twitter_misc":{"Written by":"Cassio Gusson","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/#article","isPartOf":{"@id":"https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/"},"author":{"name":"Cassio Gusson","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/2f9689f2b7291a5cceccd9685315d681"},"headline":"El poder computacional de Bitcoin cae un 9,95% tras alcanzar una tasa de hash r\u00e9cord","datePublished":"2024-09-20T10:00:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/"},"wordCount":494,"publisher":{"@id":"https:\/\/www.criptofacil.com\/es\/#organization"},"image":{"@id":"https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/#primaryimage"},"thumbnailUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/comprar-bitcoin.png","keywords":["Bitcoin","Criptomonedas","Mercado","Titular"],"articleSection":["Mercado"],"inLanguage":"es","copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.criptofacil.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/","url":"https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/","name":"El poder computacional de Bitcoin cae un 9,95% tras alcanzar una tasa de hash r\u00e9cord","isPartOf":{"@id":"https:\/\/www.criptofacil.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/#primaryimage"},"image":{"@id":"https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/#primaryimage"},"thumbnailUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/comprar-bitcoin.png","datePublished":"2024-09-20T10:00:26+00:00","description":"El poder computacional de la red de Bitcoin registr\u00f3 una ca\u00edda del 9,95% despu\u00e9s de alcanzar un r\u00e9cord hist\u00f3rico de 693 exahashes por segundo (EH\/s).","breadcrumb":{"@id":"https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/#primaryimage","url":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/comprar-bitcoin.png","contentUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/comprar-bitcoin.png","width":1445,"height":783,"caption":"El poder computacional de Bitcoin cae un 9,95% tras alcanzar una tasa de hash r\u00e9cord"},{"@type":"BreadcrumbList","@id":"https:\/\/www.criptofacil.com\/es\/el-poder-computacional-de-bitcoin-cae-un-995-tras-alcanzar-una-tasa-de-hash-record\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.criptofacil.com\/es\/"},{"@type":"ListItem","position":2,"name":"El poder computacional de Bitcoin cae un 9,95% tras alcanzar una tasa de hash r\u00e9cord"}]},{"@type":"WebSite","@id":"https:\/\/www.criptofacil.com\/es\/#website","url":"https:\/\/www.criptofacil.com\/es\/","name":"CriptoF\u00e1cil Espa\u00f1ol","description":"Noticias sobre Bitcoin, Criptomonedas, DeFi, NFT, Web3 y Blockchain","publisher":{"@id":"https:\/\/www.criptofacil.com\/es\/#organization"},"alternateName":"CriptoF\u00e1cil","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.criptofacil.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.criptofacil.com\/es\/#organization","name":"CriptoF\u00e1cil","url":"https:\/\/www.criptofacil.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png","contentUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png","width":424,"height":104,"caption":"CriptoF\u00e1cil"},"image":{"@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/criptomoedasfacil","https:\/\/x.com\/criptofacil","https:\/\/youtube.com\/channel\/UCak-HWmXEqeC3KOjTN9Fr-Q?si=lWaoQK8jh5CRg1qt","https:\/\/www.instagram.com\/criptofacil\/","https:\/\/www.linkedin.com\/company\/criptofacil\/","https:\/\/t.me\/criptomoedasfacil"]},{"@type":"Person","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/2f9689f2b7291a5cceccd9685315d681","name":"Cassio Gusson","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ab0c8f1d9f613e8ae33731332feb0b1bc8860571d0d49118f9fe63403adc37cd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab0c8f1d9f613e8ae33731332feb0b1bc8860571d0d49118f9fe63403adc37cd?s=96&d=mm&r=g","caption":"Cassio Gusson"},"description":"C\u00e1ssio Gusson \u00e9 jornalista h\u00e1 mais de 20 anos com mais de 10 anos de experi\u00eancia no mercado de criptomoedas. \u00c9 formado em jornalismo pela FACCAMP e com p\u00f3s-gradua\u00e7\u00e3o em Globaliza\u00e7\u00e3o e Cultura. Ao longo de sua carreira entrevistou grandes personalidades como Adam Back, Bill Clinton, Henrique Meirelles, entre outros. Al\u00e9m de participar de importantes f\u00f3runs multilaterais como G20 e FMI. C\u00e1ssio migrou do poder p\u00fablico para o setor de blockchain e criptomoedas por acreditar no potencial transformador desta tecnologia para moldar o novo futuro da economia digital.","sameAs":["http:\/\/www.criptomoedasfacil.com","https:\/\/www.linkedin.com\/in\/cassio-gusson-440ab7177\/"],"url":"https:\/\/www.criptofacil.com\/es\/author\/cassio-gusson\/"}]}},"_links":{"self":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts\/2376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/comments?post=2376"}],"version-history":[{"count":1,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts\/2376\/revisions"}],"predecessor-version":[{"id":2378,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts\/2376\/revisions\/2378"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/media\/2377"}],"wp:attachment":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/media?parent=2376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/categories?post=2376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/tags?post=2376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}