{"id":2313,"date":"2024-09-18T18:10:24","date_gmt":"2024-09-18T18:10:24","guid":{"rendered":"https:\/\/www.criptofacil.com\/es\/?p=2313"},"modified":"2024-09-18T18:10:24","modified_gmt":"2024-09-18T18:10:24","slug":"pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista","status":"publish","type":"post","link":"https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/","title":{"rendered":"POL, anteriormente conocida como MATIC, ha tocado fondo y est\u00e1 lista para un nuevo repunte, dice analista"},"content":{"rendered":"<p>La criptomoneda MATIC, de la red Polygon, que recientemente se convirti\u00f3 en POL, ha sido una de las que peor rendimiento ha tenido en t\u00e9rminos de valorizaci\u00f3n este a\u00f1o, acumulando una ca\u00edda de m\u00e1s del 62%.<\/p>\n<p>Sin embargo, el analista Michael Ebiekutan sugiere que el activo podr\u00eda haber alcanzado un punto de inflexi\u00f3n y hay se\u00f1ales de un posible suelo en su precio.<\/p>\n<p>Despu\u00e9s de alcanzar un m\u00e1ximo anual de 1,29 USD el 13 de marzo, POL\/MATIC se desplom\u00f3 m\u00e1s del 70%, situ\u00e1ndose actualmente en un rango de 0,36 a 0,39 USD. Seg\u00fan datos de la plataforma IntoTheBlock, en este rango de precios, los inversores adquirieron m\u00e1s de 7 mil millones de tokens.<\/p>\n<p>De acuerdo con Ebiekutan, esta fuerte demanda en torno a este nivel podr\u00eda hacer que los inversores defiendan el precio, evitando una ca\u00edda m\u00e1s pronunciada.<\/p>\n<p>\u201cSi MATIC cae por debajo de 0,36 USD, podr\u00edamos ver m\u00e1s presi\u00f3n de venta. No obstante, este rango de precios tiene un gran soporte, lo que podr\u00eda indicar que hemos encontrado un suelo\u201d, afirm\u00f3 el analista.<\/p>\n<ul>\n<li>Lee tambi\u00e9n: Empresa \u2018abandona\u2019 la miner\u00eda de Bitcoin y comienza a comprar BTC: \u2018mucho m\u00e1s lucrativo\u2019<\/li>\n<\/ul>\n<h2>An\u00e1lisis de la criptomoneda POL, anteriormente MATIC<\/h2>\n<p>Otro dato relevante destacado por Ebiekutan es el \u00edndice MVRV (Market Value to Realized Value), que mide las ganancias o p\u00e9rdidas promedio de las direcciones que compraron el token en un determinado per\u00edodo. Seg\u00fan datos de Santiment, el MVRV de 30, 60, 90, 180 y 365 d\u00edas para MATIC est\u00e1 por debajo de cero, lo que indica que la mayor\u00eda de los inversores est\u00e1n operando con p\u00e9rdidas.<\/p>\n<p>Adem\u00e1s, el \u00edndice de 365 d\u00edas, en particular, muestra una p\u00e9rdida del 96,9%, lo que podr\u00eda ser un fuerte indicador de que el precio ha alcanzado su punto m\u00e1s bajo. El analista se\u00f1ala que cuando el MVRV llega a estos niveles bajos, es un buen indicio de que el precio ha encontrado un soporte importante.<\/p>\n<p>No obstante, Ebiekutan tambi\u00e9n observ\u00f3 que el Valor Total Bloqueado (TVL) en la red Polygon se ha mantenido estable entre 800 y 900 millones de USD en el \u00faltimo a\u00f1o, lo que indica una falta de inter\u00e9s renovado en proyectos de finanzas descentralizadas (DeFi) en la blockchain de Polygon.<\/p>\n<p>\u201cEsto demuestra que, a pesar de la correcci\u00f3n del precio, a\u00fan no ha habido un aumento significativo en la actividad DeFi en la red, lo que podr\u00eda impulsar una recuperaci\u00f3n m\u00e1s fuerte\u201d, explic\u00f3.<\/p>\n<p>A corto plazo, Ebiekutan cree que POL\/MATIC podr\u00eda iniciar una recuperaci\u00f3n si logra superar las medias m\u00f3viles de 50 y 200 d\u00edas. Se\u00f1ala que si el precio de la criptomoneda se mantiene por encima de los 0,5812 USD, podr\u00eda haber un rally significativo.<\/p>\n<p>Sin embargo, el inter\u00e9s abierto (open interest) en el mercado de derivados de MATIC est\u00e1 en su nivel m\u00e1s bajo en tres a\u00f1os, lo que puede indicar una actitud cautelosa por parte de los inversores. Seg\u00fan datos de Coinglass, el inter\u00e9s abierto ha ca\u00eddo un 93% desde su pico hist\u00f3rico de 438,8 millones de USD en febrero, reflejando un comportamiento de aversi\u00f3n al riesgo en el mercado.<\/p>\n<p>Por otro lado, indicadores de momentum como el \u00cdndice de Fuerza Relativa (RSI) y el Awesome Oscillator (AO) siguen ligeramente por debajo de los niveles neutrales, lo que indica una leve tendencia bajista.<\/p>\n<p>\u201cSi el precio de MATIC cierra por debajo de 0,3578 USD, podr\u00edamos ver una nueva ola de ventas, invalidando el escenario de recuperaci\u00f3n\u201d, concluy\u00f3 Ebiekutan.<\/p>\n<ul>\n<li>Lee tambi\u00e9n: <a href=\"https:\/\/www.criptofacil.com\/es\/las-criptomonedas-pueden-experimentar-una-subida-en-octubre-con-senales-de-ballenas-y-recortes-de-tasas\/\">Las criptomonedas pueden experimentar una subida en octubre con se\u00f1ales de ballenas y recortes de tasas<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La criptomoneda MATIC, de la red Polygon, que recientemente se convirti\u00f3 en POL, ha sido una de las que peor rendimiento ha tenido en t\u00e9rminos de valorizaci\u00f3n este a\u00f1o, acumulando una ca\u00edda de m\u00e1s del 62%. Sin embargo, el analista Michael Ebiekutan sugiere que el activo podr\u00eda haber alcanzado un punto de inflexi\u00f3n y hay [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":2314,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1760],"tags":[1793,1766,1779,1771,1861,1767,1913,1862,1816],"class_list":["post-2313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado","tag-altcoin","tag-analisis","tag-criptoactivos","tag-criptomonedas","tag-matic","tag-mercado","tag-pol","tag-polygon","tag-super-titular"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>POL, anteriormente conocida como MATIC, ha tocado fondo y est\u00e1 lista para un nuevo repunte, dice analista<\/title>\n<meta name=\"description\" content=\"La criptomoneda Polygon (MATIC), que recientemente fue rebautizada como POL, ha sido una de las de peor desempe\u00f1o en t\u00e9rminos de valorizaci\u00f3n este a\u00f1o\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"POL, anteriormente conocida como MATIC, ha tocado fondo y est\u00e1 lista para un nuevo repunte, dice analista\" \/>\n<meta property=\"og:description\" content=\"La criptomoneda Polygon (MATIC), que recientemente fue rebautizada como POL, ha sido una de las de peor desempe\u00f1o en t\u00e9rminos de valorizaci\u00f3n este a\u00f1o\" \/>\n<meta property=\"og:site_name\" content=\"CriptoF\u00e1cil Espa\u00f1ol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/criptomoedasfacil\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-18T18:10:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/solana-migrara-matic-por-pol-1536x806-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"806\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cassio Gusson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@criptofacil\" \/>\n<meta name=\"twitter:site\" content=\"@criptofacil\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cassio Gusson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/\"},\"author\":{\"name\":\"Cassio Gusson\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/2f9689f2b7291a5cceccd9685315d681\"},\"headline\":\"POL, anteriormente conocida como MATIC, ha tocado fondo y est\u00e1 lista para un nuevo repunte, dice analista\",\"datePublished\":\"2024-09-18T18:10:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/\"},\"wordCount\":647,\"publisher\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/solana-migrara-matic-por-pol-1536x806-1.jpg\",\"keywords\":[\"Altcoin\",\"Analisis\",\"Criptoactivos\",\"Criptomonedas\",\"MATIC\",\"Mercado\",\"POL\",\"Polygon\",\"Super Titular\"],\"articleSection\":[\"Mercado\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.criptofacil.com\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/\",\"url\":\"https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/\",\"name\":\"POL, anteriormente conocida como MATIC, ha tocado fondo y est\u00e1 lista para un nuevo repunte, dice analista\",\"isPartOf\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/solana-migrara-matic-por-pol-1536x806-1.jpg\",\"datePublished\":\"2024-09-18T18:10:24+00:00\",\"description\":\"La criptomoneda Polygon (MATIC), que recientemente fue rebautizada como POL, ha sido una de las de peor desempe\u00f1o en t\u00e9rminos de valorizaci\u00f3n este a\u00f1o\",\"breadcrumb\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/#primaryimage\",\"url\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/solana-migrara-matic-por-pol-1536x806-1.jpg\",\"contentUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/solana-migrara-matic-por-pol-1536x806-1.jpg\",\"width\":1536,\"height\":806,\"caption\":\"POL, anteriormente conocida como MATIC, ha tocado fondo y est\u00e1 lista para un nuevo repunte, dice analista\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.criptofacil.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"POL, anteriormente conocida como MATIC, ha tocado fondo y est\u00e1 lista para un nuevo repunte, dice analista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#website\",\"url\":\"https:\/\/www.criptofacil.com\/es\/\",\"name\":\"CriptoF\u00e1cil Espa\u00f1ol\",\"description\":\"Noticias sobre Bitcoin, Criptomonedas, DeFi, NFT, Web3 y Blockchain\",\"publisher\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#organization\"},\"alternateName\":\"CriptoF\u00e1cil\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.criptofacil.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#organization\",\"name\":\"CriptoF\u00e1cil\",\"url\":\"https:\/\/www.criptofacil.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png\",\"contentUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png\",\"width\":424,\"height\":104,\"caption\":\"CriptoF\u00e1cil\"},\"image\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/criptomoedasfacil\",\"https:\/\/x.com\/criptofacil\",\"https:\/\/youtube.com\/channel\/UCak-HWmXEqeC3KOjTN9Fr-Q?si=lWaoQK8jh5CRg1qt\",\"https:\/\/www.instagram.com\/criptofacil\/\",\"https:\/\/www.linkedin.com\/company\/criptofacil\/\",\"https:\/\/t.me\/criptomoedasfacil\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/2f9689f2b7291a5cceccd9685315d681\",\"name\":\"Cassio Gusson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ab0c8f1d9f613e8ae33731332feb0b1bc8860571d0d49118f9fe63403adc37cd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ab0c8f1d9f613e8ae33731332feb0b1bc8860571d0d49118f9fe63403adc37cd?s=96&d=mm&r=g\",\"caption\":\"Cassio Gusson\"},\"description\":\"C\u00e1ssio Gusson \u00e9 jornalista h\u00e1 mais de 20 anos com mais de 10 anos de experi\u00eancia no mercado de criptomoedas. \u00c9 formado em jornalismo pela FACCAMP e com p\u00f3s-gradua\u00e7\u00e3o em Globaliza\u00e7\u00e3o e Cultura. Ao longo de sua carreira entrevistou grandes personalidades como Adam Back, Bill Clinton, Henrique Meirelles, entre outros. Al\u00e9m de participar de importantes f\u00f3runs multilaterais como G20 e FMI. C\u00e1ssio migrou do poder p\u00fablico para o setor de blockchain e criptomoedas por acreditar no potencial transformador desta tecnologia para moldar o novo futuro da economia digital.\",\"sameAs\":[\"http:\/\/www.criptomoedasfacil.com\",\"https:\/\/www.linkedin.com\/in\/cassio-gusson-440ab7177\/\"],\"url\":\"https:\/\/www.criptofacil.com\/es\/author\/cassio-gusson\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"POL, anteriormente conocida como MATIC, ha tocado fondo y est\u00e1 lista para un nuevo repunte, dice analista","description":"La criptomoneda Polygon (MATIC), que recientemente fue rebautizada como POL, ha sido una de las de peor desempe\u00f1o en t\u00e9rminos de valorizaci\u00f3n este a\u00f1o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/","og_locale":"es_ES","og_type":"article","og_title":"POL, anteriormente conocida como MATIC, ha tocado fondo y est\u00e1 lista para un nuevo repunte, dice analista","og_description":"La criptomoneda Polygon (MATIC), que recientemente fue rebautizada como POL, ha sido una de las de peor desempe\u00f1o en t\u00e9rminos de valorizaci\u00f3n este a\u00f1o","og_site_name":"CriptoF\u00e1cil Espa\u00f1ol","article_publisher":"https:\/\/www.facebook.com\/criptomoedasfacil","article_published_time":"2024-09-18T18:10:24+00:00","og_image":[{"width":1536,"height":806,"url":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/solana-migrara-matic-por-pol-1536x806-1.jpg","type":"image\/jpeg"}],"author":"Cassio Gusson","twitter_card":"summary_large_image","twitter_creator":"@criptofacil","twitter_site":"@criptofacil","twitter_misc":{"Written by":"Cassio Gusson","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/#article","isPartOf":{"@id":"https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/"},"author":{"name":"Cassio Gusson","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/2f9689f2b7291a5cceccd9685315d681"},"headline":"POL, anteriormente conocida como MATIC, ha tocado fondo y est\u00e1 lista para un nuevo repunte, dice analista","datePublished":"2024-09-18T18:10:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/"},"wordCount":647,"publisher":{"@id":"https:\/\/www.criptofacil.com\/es\/#organization"},"image":{"@id":"https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/#primaryimage"},"thumbnailUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/solana-migrara-matic-por-pol-1536x806-1.jpg","keywords":["Altcoin","Analisis","Criptoactivos","Criptomonedas","MATIC","Mercado","POL","Polygon","Super Titular"],"articleSection":["Mercado"],"inLanguage":"es","copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.criptofacil.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/","url":"https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/","name":"POL, anteriormente conocida como MATIC, ha tocado fondo y est\u00e1 lista para un nuevo repunte, dice analista","isPartOf":{"@id":"https:\/\/www.criptofacil.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/#primaryimage"},"image":{"@id":"https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/#primaryimage"},"thumbnailUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/solana-migrara-matic-por-pol-1536x806-1.jpg","datePublished":"2024-09-18T18:10:24+00:00","description":"La criptomoneda Polygon (MATIC), que recientemente fue rebautizada como POL, ha sido una de las de peor desempe\u00f1o en t\u00e9rminos de valorizaci\u00f3n este a\u00f1o","breadcrumb":{"@id":"https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/#primaryimage","url":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/solana-migrara-matic-por-pol-1536x806-1.jpg","contentUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/solana-migrara-matic-por-pol-1536x806-1.jpg","width":1536,"height":806,"caption":"POL, anteriormente conocida como MATIC, ha tocado fondo y est\u00e1 lista para un nuevo repunte, dice analista"},{"@type":"BreadcrumbList","@id":"https:\/\/www.criptofacil.com\/es\/pol-anteriormente-conocida-como-matic-ha-tocado-fondo-y-esta-lista-para-un-nuevo-repunte-dice-analista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.criptofacil.com\/es\/"},{"@type":"ListItem","position":2,"name":"POL, anteriormente conocida como MATIC, ha tocado fondo y est\u00e1 lista para un nuevo repunte, dice analista"}]},{"@type":"WebSite","@id":"https:\/\/www.criptofacil.com\/es\/#website","url":"https:\/\/www.criptofacil.com\/es\/","name":"CriptoF\u00e1cil Espa\u00f1ol","description":"Noticias sobre Bitcoin, Criptomonedas, DeFi, NFT, Web3 y Blockchain","publisher":{"@id":"https:\/\/www.criptofacil.com\/es\/#organization"},"alternateName":"CriptoF\u00e1cil","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.criptofacil.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.criptofacil.com\/es\/#organization","name":"CriptoF\u00e1cil","url":"https:\/\/www.criptofacil.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png","contentUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png","width":424,"height":104,"caption":"CriptoF\u00e1cil"},"image":{"@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/criptomoedasfacil","https:\/\/x.com\/criptofacil","https:\/\/youtube.com\/channel\/UCak-HWmXEqeC3KOjTN9Fr-Q?si=lWaoQK8jh5CRg1qt","https:\/\/www.instagram.com\/criptofacil\/","https:\/\/www.linkedin.com\/company\/criptofacil\/","https:\/\/t.me\/criptomoedasfacil"]},{"@type":"Person","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/2f9689f2b7291a5cceccd9685315d681","name":"Cassio Gusson","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ab0c8f1d9f613e8ae33731332feb0b1bc8860571d0d49118f9fe63403adc37cd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab0c8f1d9f613e8ae33731332feb0b1bc8860571d0d49118f9fe63403adc37cd?s=96&d=mm&r=g","caption":"Cassio Gusson"},"description":"C\u00e1ssio Gusson \u00e9 jornalista h\u00e1 mais de 20 anos com mais de 10 anos de experi\u00eancia no mercado de criptomoedas. \u00c9 formado em jornalismo pela FACCAMP e com p\u00f3s-gradua\u00e7\u00e3o em Globaliza\u00e7\u00e3o e Cultura. Ao longo de sua carreira entrevistou grandes personalidades como Adam Back, Bill Clinton, Henrique Meirelles, entre outros. Al\u00e9m de participar de importantes f\u00f3runs multilaterais como G20 e FMI. C\u00e1ssio migrou do poder p\u00fablico para o setor de blockchain e criptomoedas por acreditar no potencial transformador desta tecnologia para moldar o novo futuro da economia digital.","sameAs":["http:\/\/www.criptomoedasfacil.com","https:\/\/www.linkedin.com\/in\/cassio-gusson-440ab7177\/"],"url":"https:\/\/www.criptofacil.com\/es\/author\/cassio-gusson\/"}]}},"_links":{"self":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts\/2313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/comments?post=2313"}],"version-history":[{"count":1,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts\/2313\/revisions"}],"predecessor-version":[{"id":2315,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts\/2313\/revisions\/2315"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/media\/2314"}],"wp:attachment":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/media?parent=2313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/categories?post=2313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/tags?post=2313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}