{"id":2144,"date":"2024-09-16T12:29:44","date_gmt":"2024-09-16T12:29:44","guid":{"rendered":"https:\/\/www.criptofacil.com\/es\/?p=2144"},"modified":"2024-09-16T12:29:44","modified_gmt":"2024-09-16T12:29:44","slug":"bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump","status":"publish","type":"post","link":"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/","title":{"rendered":"Bitcoin Hoy 16\/09\/2024: BTC y ETH retroceden tras intento de asesinato de Trump"},"content":{"rendered":"<p>El precio de Bitcoin registr\u00f3 una ca\u00edda del 1,9% en las \u00faltimas 24 horas, cotizando alrededor de $58.780 al momento de la redacci\u00f3n de este art\u00edculo. En reales, cada BTC tiene un costo de R$ 327.288.<\/p>\n<p>Adem\u00e1s, Ethereum, la segunda mayor criptomoneda por valor de mercado, sufri\u00f3 una ca\u00edda del 4,2% en el mismo per\u00edodo y ahora se intercambia a $2.304. Otras altcoins tambi\u00e9n muestran bajas este lunes 16.<\/p>\n<p>Por ejemplo, BNB retrocedi\u00f3 un 1,0% en las \u00faltimas 24 horas, cotizando a $548,05. Solana cay\u00f3 un 2,6% a $132,06. Mientras tanto, XRP y Dogecoin retrocedieron 2,1% y 2,5%, respectivamente, a $0,57 y $0,10. Cerrando el Top 10, Toncoin sufri\u00f3 una ca\u00edda diaria del 1,4%, con un precio actual de $5,52.<\/p>\n<p>Con estas bajas en las \u00faltimas 24 horas, el valor total del mercado global de criptomonedas se sit\u00faa en $2,13 billones, con una ca\u00edda diaria del 3,7%. La dominancia de Bitcoin frente a los dem\u00e1s criptoactivos est\u00e1 en 54,4%, mientras que la de Ethereum se encuentra en 13%.<\/p>\n<ul>\n<li>Lee tambi\u00e9n: Binance Labs anuncia mega inversi\u00f3n en protocolo de RWA<\/li>\n<\/ul>\n<h2><strong>Mercado de Bitcoin y criptomonedas<\/strong><\/h2>\n<p>Estos movimientos bajistas en los precios ocurren tras un nuevo intento de asesinato contra el candidato presidencial de los Estados Unidos, Donald Trump, durante el fin de semana. Seg\u00fan el FBI, se est\u00e1 investigando los disparos que ocurrieron en el club de golf \u00abTrump International Golf Club\u00bb en Florida, donde Trump se encontraba jugando.<\/p>\n<p>Anthony Guglielmi, Jefe de Comunicaciones del Servicio Secreto de los Estados Unidos, declar\u00f3:<\/p>\n<p>\u201cEl Servicio Secreto, junto con la Oficina del Sheriff del Condado de Palm Beach, est\u00e1 investigando un incidente de protecci\u00f3n que involucr\u00f3 al expresidente Donald Trump, ocurrido poco antes de las 2 de la tarde. El expresidente est\u00e1 a salvo\u201d.<\/p>\n<p>El movimiento de precios de Bitcoin y otras criptomonedas tambi\u00e9n se produce en v\u00edsperas de un posible recorte en las tasas de inter\u00e9s en los Estados Unidos. La decisi\u00f3n se espera para la pr\u00f3xima reuni\u00f3n de la Reserva Federal (Fed), el banco central de EE. UU.<\/p>\n<p>Durante el fin de semana, Bitcoin alcanz\u00f3 un pico de aproximadamente $60.600. Sin embargo, el precio retrocedi\u00f3 a unos $58.551, seg\u00fan datos de CoinGecko.<\/p>\n<p>El mercado se ha mostrado cauteloso a medida que se acerca la pr\u00f3xima reuni\u00f3n del Comit\u00e9 Federal de Mercado Abierto (FOMC), programada para esta semana. Inversores y responsables de pol\u00edticas est\u00e1n atentos a la posibilidad de un anuncio sobre la reducci\u00f3n de tasas de inter\u00e9s, lo que podr\u00eda tener un impacto significativo en el mercado de criptomonedas y otros activos de riesgo.<\/p>\n<ul>\n<li>Lee tambi\u00e9n: <a href=\"https:\/\/www.criptofacil.com\/es\/antigua-makerdao-votara-para-vender-todo-su-wbtc\/\">Antigua MakerDAO votar\u00e1 para vender todo su wBTC<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>El precio de Bitcoin registr\u00f3 una ca\u00edda del 1,9% en las \u00faltimas 24 horas, cotizando alrededor de $58.780 al momento de la redacci\u00f3n de este art\u00edculo. En reales, cada BTC tiene un costo de R$ 327.288. Adem\u00e1s, Ethereum, la segunda mayor criptomoneda por valor de mercado, sufri\u00f3 una ca\u00edda del 4,2% en el mismo per\u00edodo [&hellip;]<\/p>\n","protected":false},"author":87,"featured_media":2145,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1760],"tags":[1766,1781,1785,1782,1779,1771,1789,1798,1825,1777,1767,1788,1816],"class_list":["post-2144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado","tag-analisis","tag-bitcoin","tag-bitcoin-hoy","tag-btc","tag-criptoactivos","tag-criptomonedas","tag-donald-trump","tag-economia","tag-ee-uu","tag-estados-unidos","tag-mercado","tag-precio-bitcoin","tag-super-titular"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bitcoin Hoy 16\/09\/2024: BTC y ETH retroceden tras intento de asesinato de Trump<\/title>\n<meta name=\"description\" content=\"El precio de Bitcoin registr\u00f3 una ca\u00edda del 1,9% en las \u00faltimas 24 horas, cotizando alrededor de $58.780 al momento de la redacci\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bitcoin Hoy 16\/09\/2024: BTC y ETH retroceden tras intento de asesinato de Trump\" \/>\n<meta property=\"og:description\" content=\"El precio de Bitcoin registr\u00f3 una ca\u00edda del 1,9% en las \u00faltimas 24 horas, cotizando alrededor de $58.780 al momento de la redacci\u00f3n\" \/>\n<meta property=\"og:site_name\" content=\"CriptoF\u00e1cil Espa\u00f1ol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/criptomoedasfacil\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-16T12:29:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/bitcoin-ethereum-diferencas-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"840\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lorena Amaro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@criptofacil\" \/>\n<meta name=\"twitter:site\" content=\"@criptofacil\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lorena Amaro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/\"},\"author\":{\"name\":\"Lorena Amaro\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/f7db6af1a8925dc60344ea9183540c3e\"},\"headline\":\"Bitcoin Hoy 16\/09\/2024: BTC y ETH retroceden tras intento de asesinato de Trump\",\"datePublished\":\"2024-09-16T12:29:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/\"},\"wordCount\":448,\"publisher\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/bitcoin-ethereum-diferencas-1.jpg\",\"keywords\":[\"Analisis\",\"Bitcoin\",\"Bitcoin Hoy\",\"BTC\",\"Criptoactivos\",\"Criptomonedas\",\"Donald Trump\",\"Econom\u00eda\",\"EE.UU\",\"Estados Unidos\",\"Mercado\",\"Precio Bitcoin\",\"Super Titular\"],\"articleSection\":[\"Mercado\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.criptofacil.com\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/\",\"url\":\"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/\",\"name\":\"Bitcoin Hoy 16\/09\/2024: BTC y ETH retroceden tras intento de asesinato de Trump\",\"isPartOf\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/bitcoin-ethereum-diferencas-1.jpg\",\"datePublished\":\"2024-09-16T12:29:44+00:00\",\"description\":\"El precio de Bitcoin registr\u00f3 una ca\u00edda del 1,9% en las \u00faltimas 24 horas, cotizando alrededor de $58.780 al momento de la redacci\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/#primaryimage\",\"url\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/bitcoin-ethereum-diferencas-1.jpg\",\"contentUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/bitcoin-ethereum-diferencas-1.jpg\",\"width\":1600,\"height\":840,\"caption\":\"Bitcoin Hoy 16\/09\/2024: BTC y ETH retroceden tras intento de asesinato de Trump\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.criptofacil.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bitcoin Hoy 16\/09\/2024: BTC y ETH retroceden tras intento de asesinato de Trump\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#website\",\"url\":\"https:\/\/www.criptofacil.com\/es\/\",\"name\":\"CriptoF\u00e1cil Espa\u00f1ol\",\"description\":\"Noticias sobre Bitcoin, Criptomonedas, DeFi, NFT, Web3 y Blockchain\",\"publisher\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#organization\"},\"alternateName\":\"CriptoF\u00e1cil\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.criptofacil.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#organization\",\"name\":\"CriptoF\u00e1cil\",\"url\":\"https:\/\/www.criptofacil.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png\",\"contentUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png\",\"width\":424,\"height\":104,\"caption\":\"CriptoF\u00e1cil\"},\"image\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/criptomoedasfacil\",\"https:\/\/x.com\/criptofacil\",\"https:\/\/youtube.com\/channel\/UCak-HWmXEqeC3KOjTN9Fr-Q?si=lWaoQK8jh5CRg1qt\",\"https:\/\/www.instagram.com\/criptofacil\/\",\"https:\/\/www.linkedin.com\/company\/criptofacil\/\",\"https:\/\/t.me\/criptomoedasfacil\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/f7db6af1a8925dc60344ea9183540c3e\",\"name\":\"Lorena Amaro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.criptofacil.com\/wp-content\/uploads\/2025\/06\/avatar_user_87_1749580051-96x96.jpeg\",\"contentUrl\":\"https:\/\/www.criptofacil.com\/wp-content\/uploads\/2025\/06\/avatar_user_87_1749580051-96x96.jpeg\",\"caption\":\"Lorena Amaro\"},\"description\":\"Lorena \u00e9 jornalista e escreve sobre Bitcoin, criptomoedas, blockchain e Web3 h\u00e1 mais de 6 anos, atualmente atuando como editora-chefe do CriptoF\u00e1cil. \u00c9 formada em Comunica\u00e7\u00e3o Social\/Jornalismo pela Universidade Federal do Rio de Janeiro (UFRJ) e p\u00f3s-graduada em Produ\u00e7\u00e3o em Jornalismo Digital pela PUC-Minas. Lorena \u00e9 apaixonada por tecnologia, inova\u00e7\u00e3o e pela liberdade financeira que as criptomoedas promovem.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/lorena-amaro-2133b4a1\/\"],\"url\":\"https:\/\/www.criptofacil.com\/es\/author\/lorena-amaro\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bitcoin Hoy 16\/09\/2024: BTC y ETH retroceden tras intento de asesinato de Trump","description":"El precio de Bitcoin registr\u00f3 una ca\u00edda del 1,9% en las \u00faltimas 24 horas, cotizando alrededor de $58.780 al momento de la redacci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/","og_locale":"es_ES","og_type":"article","og_title":"Bitcoin Hoy 16\/09\/2024: BTC y ETH retroceden tras intento de asesinato de Trump","og_description":"El precio de Bitcoin registr\u00f3 una ca\u00edda del 1,9% en las \u00faltimas 24 horas, cotizando alrededor de $58.780 al momento de la redacci\u00f3n","og_site_name":"CriptoF\u00e1cil Espa\u00f1ol","article_publisher":"https:\/\/www.facebook.com\/criptomoedasfacil","article_published_time":"2024-09-16T12:29:44+00:00","og_image":[{"width":1600,"height":840,"url":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/bitcoin-ethereum-diferencas-1.jpg","type":"image\/jpeg"}],"author":"Lorena Amaro","twitter_card":"summary_large_image","twitter_creator":"@criptofacil","twitter_site":"@criptofacil","twitter_misc":{"Written by":"Lorena Amaro","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/#article","isPartOf":{"@id":"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/"},"author":{"name":"Lorena Amaro","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/f7db6af1a8925dc60344ea9183540c3e"},"headline":"Bitcoin Hoy 16\/09\/2024: BTC y ETH retroceden tras intento de asesinato de Trump","datePublished":"2024-09-16T12:29:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/"},"wordCount":448,"publisher":{"@id":"https:\/\/www.criptofacil.com\/es\/#organization"},"image":{"@id":"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/#primaryimage"},"thumbnailUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/bitcoin-ethereum-diferencas-1.jpg","keywords":["Analisis","Bitcoin","Bitcoin Hoy","BTC","Criptoactivos","Criptomonedas","Donald Trump","Econom\u00eda","EE.UU","Estados Unidos","Mercado","Precio Bitcoin","Super Titular"],"articleSection":["Mercado"],"inLanguage":"es","copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/www.criptofacil.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/","url":"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/","name":"Bitcoin Hoy 16\/09\/2024: BTC y ETH retroceden tras intento de asesinato de Trump","isPartOf":{"@id":"https:\/\/www.criptofacil.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/#primaryimage"},"image":{"@id":"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/#primaryimage"},"thumbnailUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/bitcoin-ethereum-diferencas-1.jpg","datePublished":"2024-09-16T12:29:44+00:00","description":"El precio de Bitcoin registr\u00f3 una ca\u00edda del 1,9% en las \u00faltimas 24 horas, cotizando alrededor de $58.780 al momento de la redacci\u00f3n","breadcrumb":{"@id":"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/#primaryimage","url":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/bitcoin-ethereum-diferencas-1.jpg","contentUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2024\/09\/bitcoin-ethereum-diferencas-1.jpg","width":1600,"height":840,"caption":"Bitcoin Hoy 16\/09\/2024: BTC y ETH retroceden tras intento de asesinato de Trump"},{"@type":"BreadcrumbList","@id":"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-16-09-2024-btc-y-eth-retroceden-tras-intento-de-asesinato-de-trump\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.criptofacil.com\/es\/"},{"@type":"ListItem","position":2,"name":"Bitcoin Hoy 16\/09\/2024: BTC y ETH retroceden tras intento de asesinato de Trump"}]},{"@type":"WebSite","@id":"https:\/\/www.criptofacil.com\/es\/#website","url":"https:\/\/www.criptofacil.com\/es\/","name":"CriptoF\u00e1cil Espa\u00f1ol","description":"Noticias sobre Bitcoin, Criptomonedas, DeFi, NFT, Web3 y Blockchain","publisher":{"@id":"https:\/\/www.criptofacil.com\/es\/#organization"},"alternateName":"CriptoF\u00e1cil","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.criptofacil.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.criptofacil.com\/es\/#organization","name":"CriptoF\u00e1cil","url":"https:\/\/www.criptofacil.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png","contentUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png","width":424,"height":104,"caption":"CriptoF\u00e1cil"},"image":{"@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/criptomoedasfacil","https:\/\/x.com\/criptofacil","https:\/\/youtube.com\/channel\/UCak-HWmXEqeC3KOjTN9Fr-Q?si=lWaoQK8jh5CRg1qt","https:\/\/www.instagram.com\/criptofacil\/","https:\/\/www.linkedin.com\/company\/criptofacil\/","https:\/\/t.me\/criptomoedasfacil"]},{"@type":"Person","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/f7db6af1a8925dc60344ea9183540c3e","name":"Lorena Amaro","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/www.criptofacil.com\/wp-content\/uploads\/2025\/06\/avatar_user_87_1749580051-96x96.jpeg","contentUrl":"https:\/\/www.criptofacil.com\/wp-content\/uploads\/2025\/06\/avatar_user_87_1749580051-96x96.jpeg","caption":"Lorena Amaro"},"description":"Lorena \u00e9 jornalista e escreve sobre Bitcoin, criptomoedas, blockchain e Web3 h\u00e1 mais de 6 anos, atualmente atuando como editora-chefe do CriptoF\u00e1cil. \u00c9 formada em Comunica\u00e7\u00e3o Social\/Jornalismo pela Universidade Federal do Rio de Janeiro (UFRJ) e p\u00f3s-graduada em Produ\u00e7\u00e3o em Jornalismo Digital pela PUC-Minas. Lorena \u00e9 apaixonada por tecnologia, inova\u00e7\u00e3o e pela liberdade financeira que as criptomoedas promovem.","sameAs":["https:\/\/www.linkedin.com\/in\/lorena-amaro-2133b4a1\/"],"url":"https:\/\/www.criptofacil.com\/es\/author\/lorena-amaro\/"}]}},"_links":{"self":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts\/2144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/users\/87"}],"replies":[{"embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/comments?post=2144"}],"version-history":[{"count":1,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts\/2144\/revisions"}],"predecessor-version":[{"id":2146,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts\/2144\/revisions\/2146"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/media\/2145"}],"wp:attachment":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/media?parent=2144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/categories?post=2144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/tags?post=2144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}