{"id":16243,"date":"2025-06-03T22:00:50","date_gmt":"2025-06-03T22:00:50","guid":{"rendered":"https:\/\/www.criptofacil.com\/es\/?p=16243"},"modified":"2025-06-03T18:24:30","modified_gmt":"2025-06-03T18:24:30","slug":"altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio","status":"publish","type":"post","link":"https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/","title":{"rendered":"Altcoins en foco: Ballenas acumulan 30 millones de monedas y anticipan un aumento en junio"},"content":{"rendered":"<p>Mientras que el <a href=\"https:\/\/www.criptofacil.com\/es\/mercado\/\"><strong>mercado de criptomonedas<\/strong><\/a>, especialmente el de altcoins, desaceleraba a finales de mayo, hubo un movimiento que llam&oacute; la atenci&oacute;n: <strong>las ballenas acumularon 30 millones de DOGE en la &uacute;ltima semana<\/strong>, anticipando un junio vol&aacute;til. El momento es significativo: la compra coincide con la salida de Elon Musk del Departamento de Eficiencia Gubernamental (DOGE).<\/p>\n<p>El CEO de Tesla y gran entusiasta de la memecoin DOGE dej&oacute; la direcci&oacute;n de la entidad creada por Trump la semana pasada. Esto ocurri&oacute; despu&eacute;s de que <strong>prometiera recortar 2 billones de d&oacute;lares en gastos p&uacute;blicos<\/strong>, pero solo entreg&oacute; 32 mil millones de d&oacute;lares comprobados. Como resultado, entr&oacute; en conflicto con la nueva pol&iacute;tica fiscal expansiva de Donald Trump.<\/p>\n<h2>Altcoins en foco: Dogecoin (DOGE)<\/h2>\n<p><img decoding=\"async\" class=\"size-large wp-image-321369\" src=\"https:\/\/www.criptofacil.com\/wp-content\/uploads\/2025\/06\/DOGECOIN-MUSK-TRUMP-1151x840.jpeg\" alt=\"Pre&ccedil;o Dogecoin\" width=\"1151\" height=\"840\"><\/p>\n<p>Sin embargo, a pesar del fracaso gubernamental de <a href=\"https:\/\/www.criptofacil.com\/es\/dogecoin-y-otras-criptomonedas-para-vigilar-esta-semana\/\">DOGE<\/a>, la memecoin que inspir&oacute; el nombre del departamento est&aacute; viviendo un renacimiento. Datos de Santiment muestran que las <strong>carteras con entre 1 y 100 millones de tokens han aumentado sus posiciones<\/strong>. Las apuestas podr&iacute;an estar relacionadas con el hecho de que Musk, ahora libre del gobierno, podr&iacute;a retomar su papel como principal impulsor de la moneda.<\/p>\n<p>No falta historial: en el pasado, los comentarios y <strong>manifestaciones p&uacute;blicas de Musk llevaron a DOGE a m&aacute;ximos hist&oacute;ricos<\/strong>. Ahora, con el multimillonario de vuelta al sector privado, los grandes inversores parecen estar posicion&aacute;ndose para el pr&oacute;ximo cap&iacute;tulo de esta relaci&oacute;n improbable entre un meme de internet y el hombre m&aacute;s rico del mundo.<\/p>\n<ul>\n<li>Lee tambi&eacute;n: <a href=\"https:\/\/www.criptofacil.com\/es\/bitcoin-hoy-03-06-2025\/\">Bitcoin Hoy 03\/06\/2025: BTC retrocede tras probar los US$ 106.000; altcoins destacan con el aumento de HYPE<\/a><\/li>\n<\/ul>\n<h2>Avalanche (AVAX): Confianza creciente<\/h2>\n<p><img decoding=\"async\" class=\"size-large wp-image-321371\" src=\"https:\/\/www.criptofacil.com\/wp-content\/uploads\/2025\/06\/AVAX-Preco-Crescente-1151x840.jpeg\" alt=\"Avalanche pre&ccedil;o\" width=\"1151\" height=\"840\"><\/p>\n<p><strong>AVAX<\/strong> tambi&eacute;n est&aacute; en el radar de las ballenas despu&eacute;s de anunciar que ser&aacute; la red principal de un nuevo proyecto de la franquicia de FIFA. La idea de Electronic Arts es crear una serie de activos digitales deportivos para los fan&aacute;ticos de la franquicia. En un principio, AVAX recibir&aacute; todos los NFTs de FIFA Collect.<\/p>\n<p>Adem&aacute;s, la reciente actualizaci&oacute;n <strong>Avalanche9000 tambi&eacute;n ha jugado un papel importante en la valorizaci&oacute;n de la red<\/strong>, lo que incluso ha llevado al banco brit&aacute;nico Standard Chartered a aumentar la previsi&oacute;n de precio de AVAX en 10 veces.<\/p>\n<p>Estos factores han atra&iacute;do a las ballenas hacia Avalanche, cuyo volumen de acumulaci&oacute;n de AVAX entre las carteras que m&aacute;s poseen el token ha aumentado m&aacute;s del 3.000% en los &uacute;ltimos 30 d&iacute;as, seg&uacute;n datos on-chain.<\/p>\n<ul>\n<li>Lee tambi&eacute;n: <a href=\"https:\/\/www.criptofacil.com\/es\/productos-de-ethereum-superan-a-los-de-bitcoin-y-alcanzan-un-record\/\">Productos de Ethereum superan a los de Bitcoin y alcanzan un r&eacute;cord<\/a><\/li>\n<\/ul>\n<h2>Solaxy (SLX): Novedad pr&oacute;xima<\/h2>\n<p><img decoding=\"async\" class=\"size-full wp-image-321370 aligncenter\" src=\"https:\/\/www.criptofacil.com\/wp-content\/uploads\/2025\/06\/Memecoin-Solaxy-SOLXY.png\" alt=\"Solaxy\" width=\"591\" height=\"635\"><\/p>\n<p>Adem&aacute;s de estas criptomonedas, <strong><a href=\"https:\/\/www.criptofacil.com\/es\/visit\/solaxy\" rel=\"nofollow\" target=\"_blank\">Solaxy (SLX<\/a><\/strong>) tambi&eacute;n destaca entre los inversores. En los &uacute;ltimos d&iacute;as de la preventa, el proyecto recaud&oacute; m&aacute;s de 43 millones de d&oacute;lares, encamin&aacute;ndose a convertirse en uno de los mayores &eacute;xitos del primer semestre entre las altcoins en preventa. Como el TGE (Evento de Generaci&oacute;n de Tokens) no ocurrir&aacute; hasta dentro de dos semanas, cuando el proyecto sea oficialmente lanzado, a&uacute;n no tenemos datos sobre la acumulaci&oacute;n por parte de las ballenas.<\/p>\n<p>Sin embargo, analizando los &uacute;ltimos 30 d&iacute;as, los inversores gastaron m&aacute;s de 10 millones de d&oacute;lares en tokens, lo que muestra un fuerte inter&eacute;s en la fase final del proyecto. Con un APY de staking del 93%, los tokens a&uacute;n est&aacute;n disponibles para <a href=\"https:\/\/www.criptofacil.com\/es\/visit\/solaxy\" rel=\"nofollow\" target=\"_blank\"><strong>compra en el sitio web oficial<\/strong><\/a> hasta el 15 de junio. Tras el lanzamiento, los tokens adquiridos ser&aacute;n enviados a las carteras y se liberar&aacute;n los datos on-chain.<\/p>\n<i><b>Aviso<\/b>: Este art&iacute;culo tiene solo fines informativos y no constituye asesoramiento de inversi&oacute;n ni oferta para invertir. CriptoF&aacute;cil no se responsabiliza de ning&uacute;n contenido, producto o servicio mencionado en este art&iacute;culo. Recomendamos siempre realizar su propia investigaci&oacute;n (DYOR) antes de tomar cualquier decisi&oacute;n financiera. Invierta solo lo que pueda permitirse perder.\n<\/i>","protected":false},"excerpt":{"rendered":"<p>Mientras que el mercado de criptomonedas, especialmente el de altcoins, desaceleraba a finales de mayo, hubo un movimiento que llam&oacute; la atenci&oacute;n: las ballenas acumularon 30 millones de DOGE en la &uacute;ltima semana, anticipando un junio vol&aacute;til. El momento es significativo: la compra coincide con la salida de Elon Musk del Departamento de Eficiencia Gubernamental [&hellip;]<\/p>\n","protected":false},"author":140,"featured_media":16244,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1760],"tags":[1793,1766,1877,1876,2136,1779,1771,1842,1841,1811,1767,2386,1758],"class_list":["post-16243","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado","tag-altcoin","tag-analisis","tag-avalanche","tag-avax","tag-ballenas","tag-criptoactivos","tag-criptomonedas","tag-doge","tag-dogecoin","tag-inversion","tag-mercado","tag-solaxy","tag-titular"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Altcoins en foco: Ballenas acumulan 30 millones de monedas y anticipan un aumento en junio<\/title>\n<meta name=\"description\" content=\"Grandes tenedores e inversores se posicionan al inicio de junio invirtiendo en diversas altcoins por distintos motivos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Altcoins en foco: Ballenas acumulan 30 millones de monedas y anticipan un aumento en junio\" \/>\n<meta property=\"og:description\" content=\"Grandes tenedores e inversores se posicionan al inicio de junio invirtiendo en diversas altcoins por distintos motivos.\" \/>\n<meta property=\"og:site_name\" content=\"CriptoF\u00e1cil Espa\u00f1ol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/criptomoedasfacil\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-03T22:00:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/06\/baleias-confirma-padrao-baixa-1536x806-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"806\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diego Vieira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@criptofacil\" \/>\n<meta name=\"twitter:site\" content=\"@criptofacil\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diego Vieira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/\"},\"author\":{\"name\":\"Diego Vieira\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/cf1a90acabb1093ec55d03dc41bf149d\"},\"headline\":\"Altcoins en foco: Ballenas acumulan 30 millones de monedas y anticipan un aumento en junio\",\"datePublished\":\"2025-06-03T22:00:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/\"},\"wordCount\":615,\"publisher\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/06\/baleias-confirma-padrao-baixa-1536x806-1.jpg\",\"keywords\":[\"Altcoin\",\"Analisis\",\"Avalanche\",\"AVAX\",\"Ballenas\",\"Criptoactivos\",\"Criptomonedas\",\"DOGE\",\"Dogecoin\",\"Inversi\u00f3n\",\"Mercado\",\"solaxy\",\"Titular\"],\"articleSection\":[\"Mercado\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.criptofacil.com\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/\",\"url\":\"https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/\",\"name\":\"Altcoins en foco: Ballenas acumulan 30 millones de monedas y anticipan un aumento en junio\",\"isPartOf\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/06\/baleias-confirma-padrao-baixa-1536x806-1.jpg\",\"datePublished\":\"2025-06-03T22:00:50+00:00\",\"description\":\"Grandes tenedores e inversores se posicionan al inicio de junio invirtiendo en diversas altcoins por distintos motivos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/#primaryimage\",\"url\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/06\/baleias-confirma-padrao-baixa-1536x806-1.jpg\",\"contentUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/06\/baleias-confirma-padrao-baixa-1536x806-1.jpg\",\"width\":1536,\"height\":806,\"caption\":\"Altcoins en foco: Ballenas acumulan 30 millones de monedas y anticipan un aumento en junio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.criptofacil.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Altcoins en foco: Ballenas acumulan 30 millones de monedas y anticipan un aumento en junio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#website\",\"url\":\"https:\/\/www.criptofacil.com\/es\/\",\"name\":\"CriptoF\u00e1cil Espa\u00f1ol\",\"description\":\"Noticias sobre Bitcoin, Criptomonedas, DeFi, NFT, Web3 y Blockchain\",\"publisher\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#organization\"},\"alternateName\":\"CriptoF\u00e1cil\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.criptofacil.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#organization\",\"name\":\"CriptoF\u00e1cil\",\"url\":\"https:\/\/www.criptofacil.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png\",\"contentUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png\",\"width\":424,\"height\":104,\"caption\":\"CriptoF\u00e1cil\"},\"image\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/criptomoedasfacil\",\"https:\/\/x.com\/criptofacil\",\"https:\/\/youtube.com\/channel\/UCak-HWmXEqeC3KOjTN9Fr-Q?si=lWaoQK8jh5CRg1qt\",\"https:\/\/www.instagram.com\/criptofacil\/\",\"https:\/\/www.linkedin.com\/company\/criptofacil\/\",\"https:\/\/t.me\/criptomoedasfacil\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/cf1a90acabb1093ec55d03dc41bf149d\",\"name\":\"Diego Vieira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.criptofacil.com\/wp-content\/uploads\/2024\/11\/avatar_user_140_1732549544-96x96.jpg\",\"contentUrl\":\"https:\/\/www.criptofacil.com\/wp-content\/uploads\/2024\/11\/avatar_user_140_1732549544-96x96.jpg\",\"caption\":\"Diego Vieira\"},\"description\":\"Diego Vieira \u00e9 analista e comunicador especializado em criptomoedas e blockchain, com forma\u00e7\u00e3o em Direito. Combina conhecimento t\u00e9cnico e regulat\u00f3rio para explicar o setor de forma clara e acess\u00edvel \u2014 sem investimentos pessoais no mercado, busca sempre priorizar a informa\u00e7\u00e3o.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/diegorvieira\"],\"url\":\"https:\/\/www.criptofacil.com\/es\/author\/diegovieira\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Altcoins en foco: Ballenas acumulan 30 millones de monedas y anticipan un aumento en junio","description":"Grandes tenedores e inversores se posicionan al inicio de junio invirtiendo en diversas altcoins por distintos motivos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/","og_locale":"es_ES","og_type":"article","og_title":"Altcoins en foco: Ballenas acumulan 30 millones de monedas y anticipan un aumento en junio","og_description":"Grandes tenedores e inversores se posicionan al inicio de junio invirtiendo en diversas altcoins por distintos motivos.","og_site_name":"CriptoF\u00e1cil Espa\u00f1ol","article_publisher":"https:\/\/www.facebook.com\/criptomoedasfacil","article_published_time":"2025-06-03T22:00:50+00:00","og_image":[{"width":1536,"height":806,"url":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/06\/baleias-confirma-padrao-baixa-1536x806-1.jpg","type":"image\/jpeg"}],"author":"Diego Vieira","twitter_card":"summary_large_image","twitter_creator":"@criptofacil","twitter_site":"@criptofacil","twitter_misc":{"Written by":"Diego Vieira","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/#article","isPartOf":{"@id":"https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/"},"author":{"name":"Diego Vieira","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/cf1a90acabb1093ec55d03dc41bf149d"},"headline":"Altcoins en foco: Ballenas acumulan 30 millones de monedas y anticipan un aumento en junio","datePublished":"2025-06-03T22:00:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/"},"wordCount":615,"publisher":{"@id":"https:\/\/www.criptofacil.com\/es\/#organization"},"image":{"@id":"https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/06\/baleias-confirma-padrao-baixa-1536x806-1.jpg","keywords":["Altcoin","Analisis","Avalanche","AVAX","Ballenas","Criptoactivos","Criptomonedas","DOGE","Dogecoin","Inversi\u00f3n","Mercado","solaxy","Titular"],"articleSection":["Mercado"],"inLanguage":"es","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.criptofacil.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/","url":"https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/","name":"Altcoins en foco: Ballenas acumulan 30 millones de monedas y anticipan un aumento en junio","isPartOf":{"@id":"https:\/\/www.criptofacil.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/#primaryimage"},"image":{"@id":"https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/06\/baleias-confirma-padrao-baixa-1536x806-1.jpg","datePublished":"2025-06-03T22:00:50+00:00","description":"Grandes tenedores e inversores se posicionan al inicio de junio invirtiendo en diversas altcoins por distintos motivos.","breadcrumb":{"@id":"https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/#primaryimage","url":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/06\/baleias-confirma-padrao-baixa-1536x806-1.jpg","contentUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/06\/baleias-confirma-padrao-baixa-1536x806-1.jpg","width":1536,"height":806,"caption":"Altcoins en foco: Ballenas acumulan 30 millones de monedas y anticipan un aumento en junio"},{"@type":"BreadcrumbList","@id":"https:\/\/www.criptofacil.com\/es\/altcoins-en-foco-ballenas-acumulan-30-millones-de-monedas-y-anticipan-un-aumento-en-junio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.criptofacil.com\/es\/"},{"@type":"ListItem","position":2,"name":"Altcoins en foco: Ballenas acumulan 30 millones de monedas y anticipan un aumento en junio"}]},{"@type":"WebSite","@id":"https:\/\/www.criptofacil.com\/es\/#website","url":"https:\/\/www.criptofacil.com\/es\/","name":"CriptoF\u00e1cil Espa\u00f1ol","description":"Noticias sobre Bitcoin, Criptomonedas, DeFi, NFT, Web3 y Blockchain","publisher":{"@id":"https:\/\/www.criptofacil.com\/es\/#organization"},"alternateName":"CriptoF\u00e1cil","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.criptofacil.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.criptofacil.com\/es\/#organization","name":"CriptoF\u00e1cil","url":"https:\/\/www.criptofacil.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png","contentUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png","width":424,"height":104,"caption":"CriptoF\u00e1cil"},"image":{"@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/criptomoedasfacil","https:\/\/x.com\/criptofacil","https:\/\/youtube.com\/channel\/UCak-HWmXEqeC3KOjTN9Fr-Q?si=lWaoQK8jh5CRg1qt","https:\/\/www.instagram.com\/criptofacil\/","https:\/\/www.linkedin.com\/company\/criptofacil\/","https:\/\/t.me\/criptomoedasfacil"]},{"@type":"Person","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/cf1a90acabb1093ec55d03dc41bf149d","name":"Diego Vieira","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/www.criptofacil.com\/wp-content\/uploads\/2024\/11\/avatar_user_140_1732549544-96x96.jpg","contentUrl":"https:\/\/www.criptofacil.com\/wp-content\/uploads\/2024\/11\/avatar_user_140_1732549544-96x96.jpg","caption":"Diego Vieira"},"description":"Diego Vieira \u00e9 analista e comunicador especializado em criptomoedas e blockchain, com forma\u00e7\u00e3o em Direito. Combina conhecimento t\u00e9cnico e regulat\u00f3rio para explicar o setor de forma clara e acess\u00edvel \u2014 sem investimentos pessoais no mercado, busca sempre priorizar a informa\u00e7\u00e3o.","sameAs":["https:\/\/www.linkedin.com\/in\/diegorvieira"],"url":"https:\/\/www.criptofacil.com\/es\/author\/diegovieira\/"}]}},"_links":{"self":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts\/16243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/users\/140"}],"replies":[{"embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/comments?post=16243"}],"version-history":[{"count":1,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts\/16243\/revisions"}],"predecessor-version":[{"id":16245,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts\/16243\/revisions\/16245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/media\/16244"}],"wp:attachment":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/media?parent=16243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/categories?post=16243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/tags?post=16243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}