{"id":14760,"date":"2025-05-06T17:00:05","date_gmt":"2025-05-06T17:00:05","guid":{"rendered":"https:\/\/www.criptofacil.com\/es\/?p=14760"},"modified":"2025-05-06T15:23:31","modified_gmt":"2025-05-06T15:23:31","slug":"etoro-anuncia-detalles-del-lanzamiento-de-su-ipo","status":"publish","type":"post","link":"https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/","title":{"rendered":"eToro anuncia detalles del lanzamiento de su IPO"},"content":{"rendered":"<p><strong>La corredora que ofrece servicios con criptomonedas, eToro Group, anunci\u00f3 este martes 6 de mayo el lanzamiento de la gira de presentaci\u00f3n (roadshow) para su oferta p\u00fablica inicial de acciones (IPO).<\/strong> Este anuncio trae detalles sobre el lanzamiento de la oferta, que estaba en la agenda de la empresa desde principios de a\u00f1o.<\/p>\n<p>Seg\u00fan el <a href=\"https:\/\/www.etoro.com\/en-us\/news-and-analysis\/latest-news\/press-release\/etoro-announces-launch-of-initial-public-offering\/#:~:text=New%20York%2C%20May%205%2C%202025,offered%20by%20certain%20existing%20stockholders\">comunicado<\/a> oficial de eToro, <strong>la empresa pondr\u00e1 a disposici\u00f3n 10 millones de acciones ordinarias Clase A<\/strong>. La propia eToro <strong>vender\u00e1 la mitad de las acciones<\/strong>, mientras que parte de los inversores iniciales de la empresa vender\u00e1n las otras 5 millones. eToro espera otorgar a los suscriptores una opci\u00f3n de 30 d\u00edas para comprar 1,5 millones de acciones adicionales, si la demanda supera la oferta inicial de 10 millones.<\/p>\n<p>El precio del IPO se espera que est\u00e9 entre 46,00 y 50,00 d\u00f3lares por acci\u00f3n. Adem\u00e1s, eToro ha solicitado la <strong>cotizaci\u00f3n de sus acciones<\/strong> en la bolsa tecnol\u00f3gica Nasdaq, con el s\u00edmbolo burs\u00e1til <strong>\u00abETOR\u00bb<\/strong>.<\/p>\n<p>La corretora ya hab\u00eda anunciado sus planes para el IPO en marzo, cuando registr\u00f3 la oferta ante la Comisi\u00f3n de Valores y Bolsa de EE.UU. (SEC).<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-292191\" src=\"https:\/\/www.criptofacil.com\/wp-content\/uploads\/2024\/09\/etoro.png\" alt=\"etoro\" width=\"1280\" height=\"680\" \/><\/p>\n<ul>\n<li>Lee tambi\u00e9n: <a href=\"https:\/\/www.criptofacil.com\/es\/con-34-millones-de-dolares-solaxy-busca-mejorar-el-rendimiento-y-la-seguridad-de-la-red-solana\/\">Con 34 millones de d\u00f3lares, Solaxy busca mejorar el rendimiento y la seguridad de la red Solana<\/a><\/li>\n<\/ul>\n<h2>Detalles del IPO de eToro<\/h2>\n<p>eToro ha designado a los bancos Goldman Sachs &amp; Co. LLC, Jefferies, <strong>UBS Investment Bank y Citigroup como gestores principales<\/strong> de la suscripci\u00f3n de sus acciones. Otros bancos, como Deutsche Bank Securities, BofA Securities, Cantor, entre otros, actuar\u00e1n como gestores adicionales.<\/p>\n<p>Una declaraci\u00f3n de registro en el Formulario F-1 referente a la oferta propuesta de estos t\u00edtulos ha sido presentada ante la SEC, pero a\u00fan no ha entrado en vigor. Por lo tanto,<strong> el IPO a\u00fan no tiene fecha de lanzamiento<\/strong>, ya que depende de la aprobaci\u00f3n de dicho registro por parte de la SEC.<\/p>\n<blockquote><p>\u00abEste comunicado de prensa no constituye una oferta de venta ni una solicitud para comprar ning\u00fan t\u00edtulo, y no constituir\u00e1 una oferta, solicitud ni venta en ninguna jurisdicci\u00f3n donde dicha oferta, solicitud o venta sea ilegal antes del registro o calificaci\u00f3n seg\u00fan las leyes de valores de esa jurisdicci\u00f3n\u00bb, afirm\u00f3 eToro.<\/p><\/blockquote>\n<p>Fundada en 2007 en la ciudad de Tel Aviv, Israel, eToro es una de las plataformas de negociaci\u00f3n de activos m\u00e1s conocidas y tiene presencia en m\u00e1s de 70 pa\u00edses. Seg\u00fan los n\u00fameros de la empresa, hasta septiembre de 2024 hab\u00eda m\u00e1s de<strong> 38 millones de cuentas registradas<\/strong>.<\/p>\n<p>De este total, eToro afirma que <strong>3,5 millones de cuentas ten\u00edan saldo activo en 2024<\/strong>, lo que representa un aumento del 14% en comparaci\u00f3n con el a\u00f1o anterior. La empresa alcanz\u00f3 16,6 mil millones de d\u00f3lares en 2024, un <strong>crecimiento del 73%<\/strong> respecto a 2023, y una facturaci\u00f3n total de 931 millones de d\u00f3lares en 2024, lo que representa un aumento del 46% en comparaci\u00f3n con los 639 millones de d\u00f3lares de 2023.<\/p>\n<p>En septiembre del a\u00f1o pasado, eToro acord\u00f3 pagar una multa de 1,5 millones de d\u00f3lares en EE.UU. y limitar sus operaciones con criptomonedas en el pa\u00eds.<\/p>\n<ul>\n<li>Lee tambi\u00e9n: <a href=\"https:\/\/www.criptofacil.com\/es\/reino-unido-presenta-proyecto-para-regular-stablecoins-staking-y-exchanges-de-criptomonedas\/\">Reino Unido presenta proyecto para regular stablecoins, staking y exchanges de criptomonedas<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La corredora que ofrece servicios con criptomonedas, eToro Group, anunci\u00f3 este martes 6 de mayo el lanzamiento de la gira de presentaci\u00f3n (roadshow) para su oferta p\u00fablica inicial de acciones (IPO). Este anuncio trae detalles sobre el lanzamiento de la oferta, que estaba en la agenda de la empresa desde principios de a\u00f1o. Seg\u00fan el [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":14761,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1760],"tags":[1779,1771,1958,1780,1811,1758],"class_list":["post-14760","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado","tag-criptoactivos","tag-criptomonedas","tag-etoro","tag-exchange","tag-inversion","tag-titular"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>eToro anuncia detalles del lanzamiento de su IPO<\/title>\n<meta name=\"description\" content=\"eToro divulg\u00f3 los primeros n\u00fameros de su futura oferta de acciones, con precios que podr\u00edan llegar a los 50 d\u00f3lares por acci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"eToro anuncia detalles del lanzamiento de su IPO\" \/>\n<meta property=\"og:description\" content=\"eToro divulg\u00f3 los primeros n\u00fameros de su futura oferta de acciones, con precios que podr\u00edan llegar a los 50 d\u00f3lares por acci\u00f3n.\" \/>\n<meta property=\"og:site_name\" content=\"CriptoF\u00e1cil Espa\u00f1ol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/criptomoedasfacil\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-06T17:00:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/05\/etoro-anuncia-ipo-1536x806-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"806\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Luciano Rocha\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/lucianorocha89\" \/>\n<meta name=\"twitter:site\" content=\"@criptofacil\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luciano Rocha\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/\"},\"author\":{\"name\":\"Luciano Rocha\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/14d751fbd645e7a6fac0cf7514229133\"},\"headline\":\"eToro anuncia detalles del lanzamiento de su IPO\",\"datePublished\":\"2025-05-06T17:00:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/\"},\"wordCount\":550,\"publisher\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/05\/etoro-anuncia-ipo-1536x806-1.jpg\",\"keywords\":[\"Criptoactivos\",\"Criptomonedas\",\"eToro\",\"Exchange\",\"Inversi\u00f3n\",\"Titular\"],\"articleSection\":[\"Mercado\"],\"inLanguage\":\"es\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/www.criptofacil.com\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/\",\"url\":\"https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/\",\"name\":\"eToro anuncia detalles del lanzamiento de su IPO\",\"isPartOf\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/05\/etoro-anuncia-ipo-1536x806-1.jpg\",\"datePublished\":\"2025-05-06T17:00:05+00:00\",\"description\":\"eToro divulg\u00f3 los primeros n\u00fameros de su futura oferta de acciones, con precios que podr\u00edan llegar a los 50 d\u00f3lares por acci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/#primaryimage\",\"url\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/05\/etoro-anuncia-ipo-1536x806-1.jpg\",\"contentUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/05\/etoro-anuncia-ipo-1536x806-1.jpg\",\"width\":1536,\"height\":806,\"caption\":\"eToro anuncia detalles del lanzamiento de su IPO\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.criptofacil.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"eToro anuncia detalles del lanzamiento de su IPO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#website\",\"url\":\"https:\/\/www.criptofacil.com\/es\/\",\"name\":\"CriptoF\u00e1cil Espa\u00f1ol\",\"description\":\"Noticias sobre Bitcoin, Criptomonedas, DeFi, NFT, Web3 y Blockchain\",\"publisher\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#organization\"},\"alternateName\":\"CriptoF\u00e1cil\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.criptofacil.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#organization\",\"name\":\"CriptoF\u00e1cil\",\"url\":\"https:\/\/www.criptofacil.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png\",\"contentUrl\":\"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png\",\"width\":424,\"height\":104,\"caption\":\"CriptoF\u00e1cil\"},\"image\":{\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/criptomoedasfacil\",\"https:\/\/x.com\/criptofacil\",\"https:\/\/youtube.com\/channel\/UCak-HWmXEqeC3KOjTN9Fr-Q?si=lWaoQK8jh5CRg1qt\",\"https:\/\/www.instagram.com\/criptofacil\/\",\"https:\/\/www.linkedin.com\/company\/criptofacil\/\",\"https:\/\/t.me\/criptomoedasfacil\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/14d751fbd645e7a6fac0cf7514229133\",\"name\":\"Luciano Rocha\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f5f0711dcdbc2bcd46ed1c7f3f64588d450ca5913f029dd694d3a404ef8b6230?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f5f0711dcdbc2bcd46ed1c7f3f64588d450ca5913f029dd694d3a404ef8b6230?s=96&d=mm&r=g\",\"caption\":\"Luciano Rocha\"},\"description\":\"Luciano Rocha \u00e9 redator, escritor e editor-chefe de newsletter com 7 anos de experi\u00eancia no setor de criptomoedas. Tem forma\u00e7\u00e3o em produ\u00e7\u00e3o de conte\u00fado pela Rock Content. Desde 2017, Luciano j\u00e1 escreveu mais de 5.000 artigos, tutoriais e newsletter publica\u00e7\u00f5es como o CriptoF\u00e1cil e o Money Crunch.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/luciano-rocha\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/lucianorocha89\"],\"url\":\"https:\/\/www.criptofacil.com\/es\/author\/luciano-rocha\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"eToro anuncia detalles del lanzamiento de su IPO","description":"eToro divulg\u00f3 los primeros n\u00fameros de su futura oferta de acciones, con precios que podr\u00edan llegar a los 50 d\u00f3lares por acci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/","og_locale":"es_ES","og_type":"article","og_title":"eToro anuncia detalles del lanzamiento de su IPO","og_description":"eToro divulg\u00f3 los primeros n\u00fameros de su futura oferta de acciones, con precios que podr\u00edan llegar a los 50 d\u00f3lares por acci\u00f3n.","og_site_name":"CriptoF\u00e1cil Espa\u00f1ol","article_publisher":"https:\/\/www.facebook.com\/criptomoedasfacil","article_published_time":"2025-05-06T17:00:05+00:00","og_image":[{"width":1536,"height":806,"url":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/05\/etoro-anuncia-ipo-1536x806-1.jpg","type":"image\/jpeg"}],"author":"Luciano Rocha","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/lucianorocha89","twitter_site":"@criptofacil","twitter_misc":{"Written by":"Luciano Rocha","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/#article","isPartOf":{"@id":"https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/"},"author":{"name":"Luciano Rocha","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/14d751fbd645e7a6fac0cf7514229133"},"headline":"eToro anuncia detalles del lanzamiento de su IPO","datePublished":"2025-05-06T17:00:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/"},"wordCount":550,"publisher":{"@id":"https:\/\/www.criptofacil.com\/es\/#organization"},"image":{"@id":"https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/05\/etoro-anuncia-ipo-1536x806-1.jpg","keywords":["Criptoactivos","Criptomonedas","eToro","Exchange","Inversi\u00f3n","Titular"],"articleSection":["Mercado"],"inLanguage":"es","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/www.criptofacil.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/","url":"https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/","name":"eToro anuncia detalles del lanzamiento de su IPO","isPartOf":{"@id":"https:\/\/www.criptofacil.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/#primaryimage"},"image":{"@id":"https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/05\/etoro-anuncia-ipo-1536x806-1.jpg","datePublished":"2025-05-06T17:00:05+00:00","description":"eToro divulg\u00f3 los primeros n\u00fameros de su futura oferta de acciones, con precios que podr\u00edan llegar a los 50 d\u00f3lares por acci\u00f3n.","breadcrumb":{"@id":"https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/#primaryimage","url":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/05\/etoro-anuncia-ipo-1536x806-1.jpg","contentUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/05\/etoro-anuncia-ipo-1536x806-1.jpg","width":1536,"height":806,"caption":"eToro anuncia detalles del lanzamiento de su IPO"},{"@type":"BreadcrumbList","@id":"https:\/\/www.criptofacil.com\/es\/etoro-anuncia-detalles-del-lanzamiento-de-su-ipo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.criptofacil.com\/es\/"},{"@type":"ListItem","position":2,"name":"eToro anuncia detalles del lanzamiento de su IPO"}]},{"@type":"WebSite","@id":"https:\/\/www.criptofacil.com\/es\/#website","url":"https:\/\/www.criptofacil.com\/es\/","name":"CriptoF\u00e1cil Espa\u00f1ol","description":"Noticias sobre Bitcoin, Criptomonedas, DeFi, NFT, Web3 y Blockchain","publisher":{"@id":"https:\/\/www.criptofacil.com\/es\/#organization"},"alternateName":"CriptoF\u00e1cil","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.criptofacil.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.criptofacil.com\/es\/#organization","name":"CriptoF\u00e1cil","url":"https:\/\/www.criptofacil.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png","contentUrl":"https:\/\/www.criptofacil.com\/es\/wp-content\/uploads\/sites\/2\/2025\/07\/logo-criptofacil.png","width":424,"height":104,"caption":"CriptoF\u00e1cil"},"image":{"@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/criptomoedasfacil","https:\/\/x.com\/criptofacil","https:\/\/youtube.com\/channel\/UCak-HWmXEqeC3KOjTN9Fr-Q?si=lWaoQK8jh5CRg1qt","https:\/\/www.instagram.com\/criptofacil\/","https:\/\/www.linkedin.com\/company\/criptofacil\/","https:\/\/t.me\/criptomoedasfacil"]},{"@type":"Person","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/14d751fbd645e7a6fac0cf7514229133","name":"Luciano Rocha","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.criptofacil.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f5f0711dcdbc2bcd46ed1c7f3f64588d450ca5913f029dd694d3a404ef8b6230?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f5f0711dcdbc2bcd46ed1c7f3f64588d450ca5913f029dd694d3a404ef8b6230?s=96&d=mm&r=g","caption":"Luciano Rocha"},"description":"Luciano Rocha \u00e9 redator, escritor e editor-chefe de newsletter com 7 anos de experi\u00eancia no setor de criptomoedas. Tem forma\u00e7\u00e3o em produ\u00e7\u00e3o de conte\u00fado pela Rock Content. Desde 2017, Luciano j\u00e1 escreveu mais de 5.000 artigos, tutoriais e newsletter publica\u00e7\u00f5es como o CriptoF\u00e1cil e o Money Crunch.","sameAs":["https:\/\/www.linkedin.com\/in\/luciano-rocha\/","https:\/\/x.com\/https:\/\/twitter.com\/lucianorocha89"],"url":"https:\/\/www.criptofacil.com\/es\/author\/luciano-rocha\/"}]}},"_links":{"self":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts\/14760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/comments?post=14760"}],"version-history":[{"count":1,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts\/14760\/revisions"}],"predecessor-version":[{"id":14762,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/posts\/14760\/revisions\/14762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/media\/14761"}],"wp:attachment":[{"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/media?parent=14760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/categories?post=14760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.criptofacil.com\/es\/wp-json\/wp\/v2\/tags?post=14760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}